{"id":28776,"date":"2019-09-13T17:25:17","date_gmt":"2019-09-13T17:25:17","guid":{"rendered":"https:\/\/www.camperstime.com\/cookie-richtlinie"},"modified":"2019-10-26T06:57:27","modified_gmt":"2019-10-26T06:57:27","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies","title":{"rendered":"Pol\u00edtica de cookies"},"content":{"rendered":"<h1 style=\"margin-top: -40px;\">Pol\u00edtica de cookies para <a href=\"https:\/\/www.camperstime.com\">camperstime<\/a><\/h1>\n<p>Todas as suas informa\u00e7\u00f5es pessoais recolhidas, ser\u00e3o usadas para o ajudar a tornar a sua visita no nosso site o mais produtiva e agrad\u00e1vel poss\u00edvel.<\/p>\n<p>A garantia da confidencialidade dos dados pessoais dos utilizadores do nosso site \u00e9 importante para o camperstime.<\/p>\n<p>Todas as informa\u00e7\u00f5es pessoais relativas a membros, assinantes, clientes ou visitantes que usem o camperstime ser\u00e3o tratadas em concord\u00e2ncia com a Lei da Prote\u00e7\u00e3o de Dados Pessoais de 26 de outubro de 1998 (Lei n.\u00ba 67\/98).<\/p>\n<p>A informa\u00e7\u00e3o pessoal recolhida pode incluir o seu nome, e-mail, n\u00famero de telefone e\/ou telem\u00f3vel, morada, data de nascimento e\/ou outros.<\/p>\n<p>O uso do camperstime pressup\u00f5e a aceita\u00e7\u00e3o deste <a title=\"acordo de privacidade\" href=\"http:\/\/www.politicaprivacidade.com\" rel=\"nofollow\">Acordo de privacidade<\/a>. A equipa do camperstime reserva-se ao direito de alterar este acordo sem aviso pr\u00e9vio. Deste modo, recomendamos que consulte a nossa pol\u00edtica de privacidade com regularidade de forma a estar sempre atualizado.<\/p>\n<h2>Os an\u00fancios<\/h2>\n<p>Tal como outros websites, coletamos e utilizamos informa\u00e7\u00e3o contida nos an\u00fancios. A informa\u00e7\u00e3o contida nos an\u00fancios, inclui o seu endere\u00e7o IP (Internet Protocol), o seu ISP (Internet Service Provider, como o Sapo, Clix, ou outro), o browser que utilizou ao visitar o nosso website (como o Internet Explorer ou o Firefox), o tempo da sua visita e que p\u00e1ginas visitou dentro do nosso website.<\/p>\n<h2>Cookie DoubleClick Dart<\/h2>\n<p>O Google, como fornecedor de terceiros, utiliza cookies para exibir an\u00fancios no nosso website;<\/p>\n<p>Com o cookie DART, o Google pode exibir an\u00fancios com base nas visitas que o leitor fez a outros websites na Internet;<\/p>\n<p>Os utilizadores podem desativar o cookie DART visitando a Pol\u00edtica de privacidade da rede de conte\u00fado e dos an\u00fancios do Google.<\/p>\n<h2>Os Cookies e Web Beacons<\/h2>\n<p>Utilizamos cookies para armazenar informa\u00e7\u00e3o, tais como as suas prefer\u00eancias pessoas quando visita o nosso website. Isto poder\u00e1 incluir um simples popup, ou uma liga\u00e7\u00e3o em v\u00e1rios servi\u00e7os que providenciamos, tais como f\u00f3runs.<\/p>\n<p>Em adi\u00e7\u00e3o tamb\u00e9m utilizamos publicidade de terceiros no nosso website para suportar os custos de manuten\u00e7\u00e3o. Alguns destes publicit\u00e1rios, poder\u00e3o utilizar tecnologias como os cookies e\/ou web beacons quando publicitam no nosso website, o que far\u00e1 com que esses publicit\u00e1rios (como o Google atrav\u00e9s do Google AdSense) tamb\u00e9m recebam a sua informa\u00e7\u00e3o pessoal, como o endere\u00e7o IP, o seu ISP, o seu browser, etc. Esta fun\u00e7\u00e3o \u00e9 geralmente utilizada para geotargeting (mostrar publicidade de Lisboa apenas aos leitores oriundos de Lisboa por ex.) ou apresentar publicidade direcionada a um tipo de utilizador (como mostrar publicidade de restaurante a um utilizador que visita sites de culin\u00e1ria regularmente, por ex.).<\/p>\n<p>Voc\u00ea det\u00e9m o poder de desligar os seus cookies, nas op\u00e7\u00f5es do seu browser, ou efetuando altera\u00e7\u00f5es nas ferramentas de programas Anti-Virus, como o Norton Internet Security. No entanto, isso poder\u00e1 alterar a forma como interage com o nosso website, ou outros websites. Isso poder\u00e1 afetar ou n\u00e3o permitir que fa\u00e7a logins em programas, sites ou f\u00f3runs da nossa e de outras redes.<\/p>\n<h2>Liga\u00e7\u00f5es a Sites de terceiros<\/h2>\n<p>O camperstime possui liga\u00e7\u00f5es para outros sites, os quais, a nosso ver, podem conter informa\u00e7\u00f5es \/ ferramentas \u00fateis para os nossos visitantes. A nossa pol\u00edtica de privacidade n\u00e3o \u00e9 aplicada a sites de terceiros, pelo que, caso visite outro site a partir do nosso dever\u00e1 ler a politica de privacidade do mesmo.<\/p>\n<p>N\u00e3o nos responsabilizamos pela pol\u00edtica de privacidade ou conte\u00fado presente nesses mesmos sites.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de cookies para camperstime Todas as suas informa\u00e7\u00f5es pessoais recolhidas, ser\u00e3o usadas para o ajudar a tornar a sua visita no nosso site o mais produtiva e agrad\u00e1vel poss\u00edvel. A garantia da confidencialidade dos dados pessoais dos utilizadores do nosso site \u00e9 importante para o camperstime. Todas as informa\u00e7\u00f5es pessoais relativas a membros, assinantes, &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-28776","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edtica de cookies - camperstime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de cookies - camperstime\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de cookies para camperstime Todas as suas informa\u00e7\u00f5es pessoais recolhidas, ser\u00e3o usadas para o ajudar a tornar a sua visita no nosso site o mais produtiva e agrad\u00e1vel poss\u00edvel. A garantia da confidencialidade dos dados pessoais dos utilizadores do nosso site \u00e9 importante para o camperstime. Todas as informa\u00e7\u00f5es pessoais relativas a membros, assinantes, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies\" \/>\n<meta property=\"og:site_name\" content=\"camperstime\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-26T06:57:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies\",\"url\":\"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies\",\"name\":\"Pol\u00edtica de cookies - camperstime\",\"isPartOf\":{\"@id\":\"https:\/\/www.camperstime.com\/pt-pt#website\"},\"datePublished\":\"2019-09-13T17:25:17+00:00\",\"dateModified\":\"2019-10-26T06:57:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.camperstime.com\/pt-pt\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.camperstime.com\/pt-pt#website\",\"url\":\"https:\/\/www.camperstime.com\/pt-pt\",\"name\":\"camperstime\",\"description\":\"Themen und Artikel rund um einen Campingurlaub\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.camperstime.com\/pt-pt?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de cookies - camperstime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies","og_locale":"pt_PT","og_type":"article","og_title":"Pol\u00edtica de cookies - camperstime","og_description":"Pol\u00edtica de cookies para camperstime Todas as suas informa\u00e7\u00f5es pessoais recolhidas, ser\u00e3o usadas para o ajudar a tornar a sua visita no nosso site o mais produtiva e agrad\u00e1vel poss\u00edvel. A garantia da confidencialidade dos dados pessoais dos utilizadores do nosso site \u00e9 importante para o camperstime. Todas as informa\u00e7\u00f5es pessoais relativas a membros, assinantes, ...","og_url":"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies","og_site_name":"camperstime","article_modified_time":"2019-10-26T06:57:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies","url":"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies","name":"Pol\u00edtica de cookies - camperstime","isPartOf":{"@id":"https:\/\/www.camperstime.com\/pt-pt#website"},"datePublished":"2019-09-13T17:25:17+00:00","dateModified":"2019-10-26T06:57:27+00:00","breadcrumb":{"@id":"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.camperstime.com\/pt-pt\/politica-de-cookies#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.camperstime.com\/pt-pt"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de cookies"}]},{"@type":"WebSite","@id":"https:\/\/www.camperstime.com\/pt-pt#website","url":"https:\/\/www.camperstime.com\/pt-pt","name":"camperstime","description":"Themen und Artikel rund um einen Campingurlaub","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.camperstime.com\/pt-pt?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/www.camperstime.com\/pt-pt\/wp-json\/wp\/v2\/pages\/28776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camperstime.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.camperstime.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.camperstime.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camperstime.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=28776"}],"version-history":[{"count":0,"href":"https:\/\/www.camperstime.com\/pt-pt\/wp-json\/wp\/v2\/pages\/28776\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.camperstime.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=28776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}