{"id":28674,"date":"2015-04-23T12:57:21","date_gmt":"2015-04-23T12:57:21","guid":{"rendered":"https:\/\/www.camperstime.com\/terms-and-conditions"},"modified":"2019-10-25T04:02:15","modified_gmt":"2019-10-25T04:02:15","slug":"terms-and-conditions","status":"publish","type":"page","link":"https:\/\/www.camperstime.com\/fr\/terms-and-conditions","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"<h4 style=\"margin-top:-40px;\">Politique de confidentialit\u00e9 <\/h4>\n<p>Nous sommes ravis que vous exprimez de l&rsquo;int\u00e9r\u00eat pour notre entreprise. La protection des donn\u00e9es est une priorit\u00e9  tr\u00e8s \u00e9lev\u00e9e du management de Cincomedia GmbH. L&rsquo; utilisation des pages Internet de Cincomedia GmbH est possible sans aucune indication des donn\u00e9es \u00e0 caract\u00e8re personnel. Cependant, si une personne concern\u00e9e veux utiliser des services d&rsquo;entreprise sp\u00e9ciaux via notre page Internet, le traite des donn\u00e9es \u00e0 caract\u00e8re personnel pourrait devenir n\u00e9cessaire.  Si le traitement des donn\u00e9es \u00e0 caract\u00e8re personnel est n\u00e9cessaire et il n&rsquo;y existe pas de base l\u00e9gale de tel traitement, nous acqu\u00e9rons g\u00e9n\u00e9ralement du consentement de la personne concern\u00e9e.<\/p>\n<p>Le traitement des donn\u00e9es \u00e0 caract\u00e8re personnel, comme le nom, l&rsquo; adresse, l&rsquo; adresse \u00e9lectronique (e-mail) ou la num\u00e9ro de t\u00e9l\u00e9phone de la personne concern\u00e9e doit toujours \u00eatre conforme au r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD, GDPR) et \u00e0 la r\u00e9glementation de protection des donn\u00e9es sp\u00e9cifique au pays applicable \u00e0 Cincomedia GmbH. Au moyen de cette d\u00e9claration de la protection des donn\u00e9es, notre entreprise veux informer la grande public de la nature, la port\u00e9e et la finalit\u00e9 des donn\u00e9es \u00e0 caract\u00e8re personnel que nous collectons, utilisons et traitons. En outre, au moyen de cette d\u00e9claration de la protection des donn\u00e9es, des personnes concern\u00e9es sont inform\u00e9es de votre droits.  <\/p>\n<p>Comme le responsable du traitement, Cincomedia GmbH a mis en \u0153uvre de nombreuses mesures techniques et organisationnelles pour assurer la protection la plus compl\u00e8te des donn\u00e9es \u00e0 caract\u00e8re personnel trait\u00e9es par cette page Internet. Cependant, les transmissions des donn\u00e9es sur Internet peuvent en principe comporter des lacunes de s\u00e9curit\u00e9, donc de la protection absolue ne peut pas \u00eatre garantie. De cette raison, chaque  personne concern\u00e9e est libre de nous transf\u00e9rer des donn\u00e9es \u00e0 caract\u00e8re personnel pas des moyens alternatifs, pas exemple par t\u00e9l\u00e9phone. <\/p>\n<h4>1. D\u00e9finitions <\/h4>\n<p>La d\u00e9claration de la protection des donn\u00e9es de Cincomedia GmbH est base sur les termes utilis\u00e9s par le l\u00e9gislateur europ\u00e9en pour l\u2019adoption du r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD, GDPR). Notre d\u00e9claration de la protection des donn\u00e9es doit \u00eatre lisible et compr\u00e9hensible pour la grande public, Our data protection d\u00e9claration doivent \u00eatre lisibles et compr\u00e9hensibles for the g\u00e9n\u00e9ral public, aussi bien que nos clients et partenaires commerciaux. Pour s\u2019assurer, nous aimerons d&rsquo;abord expliquer la terminologie utilis\u00e9e.<\/p>\n<p>Dans cette d\u00e9claration de la protection des donn\u00e9es, nous utilisons les termes suivants:<\/p>\n<ul style=\"list-style: none\">\n<li>\n<h4>a)\u00a0\u00a0\u00a0 Donn\u00e9es \u00e0 caract\u00e8re personnel<\/h4>\n<p>Donn\u00e9es \u00e0 caract\u00e8re personnel est toute information se rapportant \u00e0 une personne physique identifi\u00e9e ou identifiable<br \/>\n(ci-apr\u00e8s d\u00e9nomm\u00e9e \u00abpersonne concern\u00e9e\u00bb); est r\u00e9put\u00e9e \u00eatre une \u00abpersonne physique identifiable\u00bb une personne<br \/>\nphysique qui peut \u00eatre identifi\u00e9e, directement ou indirectement, notamment par r\u00e9f\u00e9rence \u00e0 un identifiant, tel qu&rsquo;un<br \/>\nnom, un num\u00e9ro d&rsquo;identification, des donn\u00e9es de localisation, un identifiant en ligne, ou \u00e0 un ou plusieurs \u00e9l\u00e9ments<br \/>\nsp\u00e9cifiques propres \u00e0 l&rsquo; identit\u00e9 physique, physiologique, g\u00e9n\u00e9tique, psychique, \u00e9conomique, culturelle ou sociale de cette personne physique.<\/p>\n<\/li>\n<li>\n<h4>b) Personne concern\u00e9e<\/h4>\n<p>La personne concern\u00e9e signifie chaqune personne physique identifi\u00e9e, dont les donn\u00e9es \u00e0 caract\u00e8re personnel sont trait\u00e9es  par la personne responsable de cet traitement.<\/p>\n<\/li>\n<li>\n<h4>c)\u00a0\u00a0\u00a0 Traitement <\/h4>\n<p>Le traitement signifie toute op\u00e9ration ou tout ensemble d&rsquo;op\u00e9rations effectu\u00e9es ou non \u00e0 l&rsquo;aide de proc\u00e9d\u00e9s automatis\u00e9s et appliqu\u00e9es \u00e0 des donn\u00e9es ou des ensembles de donn\u00e9es \u00e0 caract\u00e8re personnel, telles que la collecte, l&rsquo;enregistrement,<br \/>\nl&rsquo;organisation, la structuration, la conservation, l&rsquo;adaptation ou la modification, l&rsquo;extraction, la consultation, l&rsquo;utilisation, la communication par transmission, la diffusion ou toute autre forme de mise \u00e0 disposition, le rapprochement ou l&rsquo;interconnexion, la limitation, l&rsquo;effacement ou la destruction.<\/p>\n<\/li>\n<li>\n<h4>d)\u00a0\u00a0\u00a0Limitation du traitement<\/h4>\n<p>La limitation du traitement signifie le marquage de donn\u00e9es \u00e0 caract\u00e8re personnel conserv\u00e9es, en vue de limiter leur<br \/>\ntraitement futur.<\/p>\n<\/li>\n<li>\n<h4>e)\u00a0\u00a0\u00a0 Profilage<\/h4>\n<p>Le profilage signifie toute forme de traitement automatis\u00e9 de donn\u00e9es \u00e0 caract\u00e8re personnel consistant \u00e0 utiliser ces donn\u00e9es \u00e0 caract\u00e8re personnel pour \u00e9valuer certains aspects personnels relatifs \u00e0 une personne physique, notamment pour analyser ou pr\u00e9dire des \u00e9l\u00e9ments concernant le rendement au travail, la situation \u00e9conomique, la sant\u00e9, les pr\u00e9f\u00e9rences personnelles, les int\u00e9r\u00eats, la fiabilit\u00e9, le comportement, la localisation ou les d\u00e9placements de cette<br \/>\npersonne physique.<\/p>\n<\/li>\n<li>\n<h4>f)\u00a0\u00a0\u00a0\u00a0 Pseudonymisation<\/h4>\n<p>Le pseudonymisation signifie  le traitement de donn\u00e9es \u00e0 caract\u00e8re personnel de telle fa\u00e7on que celles-ci ne puissent plus \u00eatre attribu\u00e9es \u00e0 une personne concern\u00e9e pr\u00e9cise sans avoir recours \u00e0 des informations suppl\u00e9mentaires, pour autant que ces informations suppl\u00e9mentaires soient conserv\u00e9es s\u00e9par\u00e9ment et soumises \u00e0 des mesures techniques et organisationnelles afin de garantir que les donn\u00e9es \u00e0 caract\u00e8re personnel ne sont pas attribu\u00e9es \u00e0 une personne physique identifi\u00e9e ou identifiable.<\/p>\n<\/li>\n<li>\n<h4>g)\u00a0\u00a0\u00a0 Responsable du traitement<\/h4>\n<p>Le responsable du traitement est a personne physique ou morale, l&rsquo;autorit\u00e9 publique, le service ou un autre organisme<br \/>\nqui, seul ou conjointement avec d&rsquo;autres, d\u00e9termine les finalit\u00e9s et les moyens du traitement; lorsque les finalit\u00e9s et<br \/>\nles moyens de ce traitement sont d\u00e9termin\u00e9s par le droit de l&rsquo;Union ou le droit d&rsquo;un \u00c9tat membre, le responsable du<br \/>\ntraitement peut \u00eatre d\u00e9sign\u00e9 ou les crit\u00e8res sp\u00e9cifiques applicables \u00e0 sa d\u00e9signation peuvent \u00eatre pr\u00e9vus par le droit<br \/>\nde l&rsquo;Union ou par le droit d&rsquo;un \u00c9tat membre.<\/p>\n<\/li>\n<li>\n<h4>h)\u00a0\u00a0\u00a0 Sous-traitant<\/h4>\n<p>Le sous-traitant est la personne physique ou morale, l&rsquo;autorit\u00e9 publique, le service ou un autre organisme qui traite des<br \/>\ndonn\u00e9es \u00e0 caract\u00e8re personnel pour le compte du responsable du traitement.<\/p>\n<\/li>\n<li>\n<h4>i)\u00a0\u00a0\u00a0\u00a0\u00a0 Destinataire<\/h4>\n<p>Le destinataire est la personne physique ou morale, l&rsquo;autorit\u00e9 publique, le service ou tout autre organisme qui re\u00e7oit<br \/>\ncommunication de donn\u00e9es \u00e0 caract\u00e8re personnel, qu&rsquo;il s&rsquo;agisse ou non d&rsquo;un tiers. Toutefois, les autorit\u00e9s publiques qui sont susceptibles de recevoir communication de donn\u00e9es \u00e0 caract\u00e8re personnel dans le cadre d&rsquo;une mission d&rsquo;enqu\u00eate particuli\u00e8re conform\u00e9ment au droit de l&rsquo;Union ou au droit d&rsquo;un \u00c9tat membre ne sont pas consid\u00e9r\u00e9es comme des destinataires; le traitement de ces donn\u00e9es par les autorit\u00e9s publiques en question est conforme aux r\u00e8gles applicables en mati\u00e8re de protection des donn\u00e9es en fonction des finalit\u00e9s du traitement.<\/p>\n<\/li>\n<li>\n<h4>j)\u00a0\u00a0\u00a0\u00a0\u00a0 \u03a4iers<\/h4>\n<p>Le tiers est une personne physique ou morale, une autorit\u00e9 publique, un service ou un organisme autre que la personne<br \/>\nconcern\u00e9e, le responsable du traitement, le sous-traitant et les personnes qui, plac\u00e9es sous l&rsquo;autorit\u00e9 directe du<br \/>\nresponsable du traitement ou du sous-traitant, sont autoris\u00e9es \u00e0 traiter les donn\u00e9es \u00e0 caract\u00e8re personnel.<\/p>\n<\/li>\n<li>\n<h4>k)\u00a0\u00a0\u00a0 Consentement<\/h4>\n<p>Le consentement de la personne concern\u00e9e est toute manifestation de volont\u00e9, libre, sp\u00e9cifique, \u00e9clair\u00e9e et univoque par<br \/>\nlaquelle la personne concern\u00e9e accepte, par une d\u00e9claration ou par un acte positif clair, que des donn\u00e9es \u00e0 caract\u00e8re<br \/>\npersonnel la concernant fassent l&rsquo;objet d&rsquo;un traitement.<\/p>\n<\/li>\n<\/ul>\n<h4>2. Nom et adresse du responsable du traitement<\/h4>\n<p>Le responsable du traitement aux fins du r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD, GDPR), d&rsquo; autres lois sur la protection des donn\u00e9es applicables aux \u00c9tats membres de l&rsquo; Union europ\u00e9enne et d&rsquo; autres dispositions relatifs a la protection des donn\u00e9es est:\n<\/p>\n<p>Cincomedia GmbH<\/p>\n<p>Rosa-Hoffmann-Stra\u00dfe 33<\/p>\n<p>5020 Salzburg<\/p>\n<p>\u00d6sterreich<\/p>\n<p>Num\u00e9ro de t\u00e9l\u00e9phone: +4917637709070<\/p>\n<p>Email: info@camperstime.com<\/p>\n<p>Site Web: www.camperstime.com<\/p>\n<h4>3. Cookies<\/h4>\n<p>La site Internet de Cincomedia GmbH utilise de cookies. Les Cookies sont fichiers textes conserves sur un syst\u00e8me informatique via un programme de navigation sur le Web.<\/p>\n<p>Beaucoup des sites Internet utilisent des cookies. Beaucoup des cookies contiennent un soi-disant identifiant de cookie. Le cookie ID est un identifiant unique de cookie. Il consiste en une cha\u00eene de caract\u00e8res \u00e0 travers laquelle les sites Internet et serveurs peuvent etre assign\u00e9s sur un navigateur Internet sp\u00e9cifique dans lequel les cookies sont conserv\u00e9s. Cela permet aux sites Internet visites et aux serveurs de se diff\u00e9rencier du navigateur Internet individuel de la personne concern\u00e9e \u00e0 partir d&rsquo; autres navigateurs Internet contenants d&rsquo; autre cookies. Chaque navigateur Internet sp\u00e9cifique peut \u00eatre reconnu et identifi\u00e9 \u00e0 l&rsquo; aide de la cookie ID unique.<\/p>\n<p>Gr\u00e2ce \u00e0 l&rsquo;utilisation de cookies, Cincomedia GmbH peut fournir des utilisateurs de ce site Web des services plus conviviaux qui ne serait pas possible sans la configuration des cookies.<\/p>\n<p>Au moyen de cookie, les information et les offres sur notre site Web peuvent \u00eatre optimis\u00e9es en tenant compte de l&rsquo; utilisateur. Les cookies nous permettent, comme mentionn\u00e9 pr\u00e9c\u00e9demment, de reconna\u00eetre les utilisateurs de notre site Web. Le but de cette reconnaissance est de faciliter l&rsquo; utilisation de notre site Web pour les utilisateurs. L&rsquo; utilisateur du site Web qu&rsquo; utilise des cookies ne doit pas, par exemple, entrer des donn\u00e9es d&rsquo; acc\u00e8s chaque fois qu&rsquo; il acc\u00e8de au site, parce que c&rsquo;est pris en charge par le site Web et le cookie est ainsi conserv\u00e9 sur le system informatique de l&rsquo; utilisateur.     Un autre exemple est le cookie d\u2019un panier d&rsquo; achat sur une boutique en ligne. La boutique en ligne se souvient les produits qu\u2019un client a plac\u00e9s sur le panier d&rsquo;achat virtuel via un cookie.<\/p>\n<p>La personne concern\u00e9e peut, \u00e0 tout moment, emp\u00eacher la configuration des cookies via notre site Web au moyen de la configuration correspondante du navigateur Internet utilis\u00e9, et peut donc refuser en permanence la configuration des cookies. En outre, les cookies d\u00e9j\u00e0 configur\u00e9s peuvent \u00eatre effaces \u00e0 tout moment via un navigateur Internet ou d&rsquo; autre logiciel. Ceci est possible sur tous les navigateurs Internet populaires. Si la personne concern\u00e9e d\u00e9sactive le param\u00e9trage des cookies sur le navigateur Internet enti\u00e8rement utilisables.<\/p>\n<h4>4. La collection des donn\u00e9es et informations g\u00e9n\u00e9rales<\/h4>\n<p>Le site Web de Cincomedia GmbH collecte une s\u00e9rie des donn\u00e9es et d&rsquo; information g\u00e9n\u00e9rales quand une personne concern\u00e9e ou un syst\u00e8me automatis\u00e9 appelle le site Web. Ces donn\u00e9es et informations g\u00e9n\u00e9rales sont conserv\u00e9es dans les fichiers journaux du serveur. Collect\u00e9es peuvent \u00eatre (1) les types des navigateurs Internet et les versions utilis\u00e9s, (2) le syst\u00e8me d&rsquo; op\u00e9ration  utilis\u00e9 par le syst\u00e8me d&rsquo;acc\u00e8s, (3) le site Web \u00e0 partir duquel un syst\u00e8me d&rsquo;acc\u00e8s atteint notre site Web (soi-disant r\u00e9f\u00e9rents), (4) les sous-sites Web, (5) la date et l&rsquo; heure de l&rsquo; acc\u00e8s au site Internet, (6) une adresse de protocole Internet (IP address), (7) le fournisseur de services Internet du syst\u00e8me d&rsquo;acc\u00e8s, et (8) tout autre donn\u00e9e et information similaire pouvant \u00eatre utilis\u00e9e en cas d&rsquo; attaque de nos syst\u00e8mes informatiques.<\/p>\n<p>En utilisant ces donn\u00e9es et informations g\u00e9n\u00e9rales, Cincomedia GmbH n&rsquo; arrive pas aux conclusions sur la personne concern\u00e9e. Cette information est plut\u00f4t utilis\u00e9e pour (1) livrer correctement le contenu de notre site Web, (2) optimiser le contenu de notre site Web ainsi que sa publicit\u00e9, (3) assurer la viabilit\u00e9 \u00e0 long terme de nos syst\u00e8mes informatiques et de notre technologie de site Web, et (4) fournir autorit\u00e9s charg\u00e9es de l&rsquo;application des lois avec d&rsquo; information n\u00e9cessaire aux poursuites p\u00e9nales en cas de cyberattaque. Dont, Cincomedia GmbH analyse en mani\u00e8re statistique les donn\u00e9es et informations collect\u00e9es anonymement, dans le but d&rsquo;accro\u00eetre la protection et la s\u00e9curit\u00e9 des donn\u00e9es de notre entreprise, et d&rsquo; assurer un niveau optimal de la protection pour les donn\u00e9es \u00e0 caract\u00e8re personnel que nous traitons. Les donn\u00e9es anonymes des fichiers journaux du serveur sont conserves s\u00e9par\u00e9ment  de toutes les donn\u00e9es \u00e0 caract\u00e8re personnel fournies par la personne concern\u00e9e.<\/p>\n<h4>5. Enregistrement sur notre site Internet<\/h4>\n<p>La personne concern\u00e9e a la possibilit\u00e9 de s&rsquo; enregistrer sur le site Web du responsable du traitement \u00e0 l&rsquo; indication des donn\u00e9es \u00e0 caract\u00e8re personnel. Les donn\u00e9es \u00e0 caract\u00e8re personnel quelles vont \u00eatre transmises au responsable du traitement sont d\u00e9termin\u00e9es par le masque de saisie respectif utilis\u00e9 pour l&rsquo;enregistrement. Les donn\u00e9es \u00e0 caract\u00e8re personnel saisies par la personne concern\u00e9e sont collect\u00e9es et conserv\u00e9es exclusivement pour l&rsquo; usage interne par le responsable du traitement, \u00e0 ses propres fins. Le responsable du traitement peut demander la transmission \u00e0 un ou plusieurs processeurs (p.e. un service de colis) qui utilisent \u00e9galement des donn\u00e9es \u00e0 caract\u00e8re personnel pour un but interne imputable au responsable du traitement.<\/p>\n<p>En vous enregistrant sur le site Web du responsable du traitement, l&rsquo; adresse IP &#8211; attribu\u00e9e par le fournisseur de services Internet (ISP) et utilis\u00e9e par la personne concern\u00e9e \u2014 la date et l&rsquo; heure d&rsquo; enregistrement sont aussi conserv\u00e9es. La conservation de ces donn\u00e9es a lieu dans la contexte que c&rsquo;est le seul moyen d&rsquo; emp\u00eacher l&rsquo; utilisation abusive de nos services, et, si n\u00e9cessaire, de permettre l&rsquo; investigation des infractions commises. Dans cette mesure, la conservation de ces donn\u00e9es est n\u00e9cessaire pour s\u00e9curiser le responsable du traitement. Ces donn\u00e9es ne sont pas transmises aux tiers, sauf il existe une obligation l\u00e9gale de transmettre ces donn\u00e9es ou si la transmission servi le but des poursuites p\u00e9nales. <\/p>\n<p>L&rsquo; enregistrement de la personne concern\u00e9e par l&rsquo; indication volontaire des donn\u00e9es \u00e0 caract\u00e8re personnel est destine \u00e0 permettre le responsable du traitement d&rsquo; offrir \u00e0 la personne concern\u00e9e du contenu ou des services qui ne peuvent \u00eatre offertes qu&rsquo; aux utilisateurs enregistr\u00e9s en raison de la nature du sujet en question. Des personnes enregistr\u00e9es peuvent modifier, \u00e0 tout temps, sans contraints des donn\u00e9es \u00e0 caract\u00e8re personnel sp\u00e9cifi\u00e9es pendant l\u2019enregistrement ou de les supprimer compl\u00e8tement du stock des donn\u00e9es du responsable du traitement.<\/p>\n<p>Le responsable du traitement des donn\u00e9es doit, \u00e0 tout moment, fournir \u00e0 la demande de chaque personne concern\u00e9e des informations sur les donn\u00e9es \u00e0 caract\u00e8re personnel conserv\u00e9es sur la personne concern\u00e9e. En outre, le responsable du traitement doit corriger ou effacer les donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 la demande ou \u00e0 l&rsquo;indication de la personne concern\u00e9e, pour autant qu&rsquo; il n&rsquo; existe pas d&rsquo;obligation l\u00e9gale de conservation. Tous les employ\u00e9s du responsable du traitement sont \u00e0 la disposition de la personne concern\u00e9e comme personnes de contact. <\/p>\n<h4>6. Inscription \u00e0 nos newsletters<\/h4>\n<p>Sur le site Web de Cincomedia GmbH, les utilisateur ont la possibilite de s&rsquo; abonner aux newsletters de notre entreprise. Le masque de saisie utilis\u00e9 pour cette raison d\u00e9termine quelles donn\u00e9es \u00e0 caract\u00e8re personnel sont transmises, aussi bien qu&rsquo; \u00e0 quelle moment est la newsletter command\u00e9e par le responsable du traitement. <\/p>\n<p>Cincomedia GmbH informe r\u00e9guli\u00e8rement ses clients et ses partenaires commerciaux au moyen d&rsquo; une newsletter. La newsletter de l&rsquo; entreprise peut \u00eatre re\u00e7ue par la personne concern\u00e9e seulement si (1) la personne concern\u00e9e a une adresse e-mail valide, et (2) la personne concern\u00e9e s&rsquo; enregistre sur la newsletter. Un e-mail de confirmation va \u00eatre envoy\u00e9 pour la premier fois \u00e0 l&rsquo; adresse e-mail enregistr\u00e9e par la personne concern\u00e9e, pour des raisons l\u00e9gales, pendant la proc\u00e9dure de double opt-in. Cet e-mail de confirmation sert \u00e0 prouver si le propri\u00e9taire de l&rsquo; adresse e-mail est autorise comme une personne concern\u00e9e \u00e0 recevoir la newsletter.<\/p>\n<p>Pendant l&rsquo; inscription \u00e0  la newsletter, nous conservons aussi l&rsquo; adresse IP du syst\u00e8me informatique assign\u00e9e par le fournisseur de services Internet (ISP) et utilis\u00e9e par la personne concern\u00e9e pendant l&rsquo; inscription, aussi que la date et l&rsquo;heure d&rsquo; inscription. La collecte de ces donn\u00e9es est n\u00e9cessaire afin de comprendre la (possible) utilisation abusive d&rsquo; adresse e-mail de la personne concern\u00e9e \u00e0 une date ult\u00e9rieure, donc sert-il l&rsquo;objectif de la protection juridique du responsable du traitement.<\/p>\n<p>Les donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es dans le cadre de l&rsquo; inscription \u00e0 la newsletter sera utilis\u00e9es seulement pour envoyer notre newsletter. En plus, les inscrits \u00e0 la newsletter peuvent \u00eatre inform\u00e9s via e-mail, aussi longtemps que c&rsquo;est n\u00e9cessaire pour l&rsquo; op\u00e9ration du service de newsletter ou pour une enregistrement en question, par exemple en cas des modifications \u00e0 l&rsquo; offre de newsletter ou en cas d&rsquo; une changement des circonstances techniques. Il n&rsquo; y aura pas de transmission des donn\u00e9es \u00e0 caract\u00e8re personnel par le service de newsletter \u00e0 des tiers. L&rsquo; inscription \u00e0 notre newsletter peut \u00eatre, \u00e0 tout moment, termin\u00e9e par la personne concern\u00e9e. Le consentement \u00e0 la conservation des donn\u00e9es \u00e0 caract\u00e8re personnel que la personne concern\u00e9e a donn\u00e9 pour l&rsquo; envoi de la newsletter peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment. Aux fins de la r\u00e9vocation du consentement, un lien correspondant se trouve dans chaque newsletter. Il est \u00e9galement possible de se d\u00e9sabonner \u00e0 la newsletter \u00e0 tout moment directement sur le site Web du responsable du traitement ou de la communiquer avec le responsable du traitement d&rsquo;une mani\u00e8re diff\u00e9rente. <\/p>\n<h4>7. Newsletter-Tracking<\/h4>\n<p>La newsletter de Cincomedia GmbH contient des soi-disant pixels de suivi (tracking pixels). I448. Cela permettre une analyse statistique du succ\u00e8s ou de l&rsquo; \u00e9chec des campagnes du marketing en ligne. Fond\u00e9 sur le pixel de suivi int\u00e9gr\u00e9, Cincomedia GmbH peut voir si et quand un e-mail a \u00e9t\u00e9 ouvert par la personne concern\u00e9e et quelles liens dans l&rsquo; e-mail ont \u00e9t\u00e9 ouvertes par la personne concern\u00e9e.<\/p>\n<p>Ces donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es par les pixels de suivi contenus dans la newsletter sont conserv\u00e9es et analys\u00e9es par le responsable du traitement pour l&rsquo; optimisation de l&rsquo; exp\u00e9dition des newsletters, ainsi que pou la meilleure adaptation du contenu des futures newsletters aux int\u00e9r\u00eats de la personne concern\u00e9e. Ces donn\u00e9es \u00e0 caract\u00e8re personnel ne sont pas transmises aux tiers. Les personnes concern\u00e9es ont, \u00e0 tout moment, le droit de r\u00e9voquer leur d\u00e9claration de consentement distincte exprim\u00e9 au moyen de la proc\u00e9dure de double opt-in. Apr\u00e8s la r\u00e9vocation, ces donn\u00e9es \u00e0 caract\u00e8re personnel seront supprim\u00e9es par le responsable du traitement. Cincomedia GmbH regarde automatiquement le retrait de la r\u00e9ception de la newsletter comme une r\u00e9vocation.<\/p>\n<h4>8. Possibilit\u00e9 de contact via le site Web <\/h4>\n<p>Le site Web de Cincomedia GmbH contient des informations permettant le contact \u00e9lectronique rapide avec notre entreprise, ainsi que la communication directe avec nous, aussi comprenant une adresse g\u00e9n\u00e9rale du soi-disant courrier \u00e9lectronique (e-mail address). Si la personne concern\u00e9e contacte le responsable du traitement via e-mail ou un formulaire de contact, les donn\u00e9es \u00e0 caract\u00e8re personnel transmises par la personne concern\u00e9e sont automatiquement stock\u00e9es. Ces donn\u00e9es \u00e0 caract\u00e8re personnel transmises volontairement par la personne concern\u00e9e au responsable du traitement sont conserv\u00e9es dans le but de proc\u00e9der ou communication avec la personne concern\u00e9e. Il n&rsquo; y a pas de transmission de ces donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 des tiers. <\/p>\n<h4>9. Fonction des commentaires sur le blog du site Web<\/h4>\n<p>Cincomedia GmbH offre aux utilisateurs la possibilit\u00e9 de laisser des commentaires individuels sur des contributions de blog individuelles sur le site Web du responsable de traitement. Un blog est un portail Web accessible au public, \u00e0 travers lequel une ou plusieurs personnes appel\u00e9es les bloggeurs ou web-bloggeurs peuvent poster des articles ou recorder leurs pens\u00e9es dans de soi-disant articles de blog (blogposts). Blogposts peuvent \u00eatre comment\u00e9s par des tiers.<\/p>\n<p>Si une personne concern\u00e9e commente sur le blog publi\u00e9 sur ce site Web, ce commentaire de la personne concern\u00e9e est \u00e9galement conserv\u00e9 et publi\u00e9, ainsi que des informations sur la date du commentaire et le pseudonyme de l&rsquo; utilisateur choisi par la personne concern\u00e9e. En plus, l&rsquo; adresse IP attribu\u00e9e par le fournisseur de services Internet \u00e0 la personne concern\u00e9e est aussi record\u00e9e. Ce stockage de l&rsquo; adresse IP a lieu pour des raisons de s\u00e9curit\u00e9 et en cas que la personne concern\u00e9e viole les droits des tiers ou poste du contenu ill\u00e9gal via un commentaire. Le stockage de ces donn\u00e9es \u00e0 caract\u00e8re personnel est donc dans l\u2019int\u00e9r\u00eat du responsable du traitement des donn\u00e9es, afin qu&rsquo; il puisse disculper en cas d&rsquo; infraction. Ces donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es ne seront pas transmises \u00e0 des tiers, sauf une telle transmission est requis par la loi ou sert \u00e0 la d\u00e9fense du responsable du traitement des donn\u00e9es.<\/p>\n<h4>10. Inscription aux commentaires sur le blog du site Web <\/h4>\n<p>\nLes commentaires sur le blog de Cincomedia GmbH peuvent \u00eatre inscrits par des tiers. En particulier, il est possible qu\u2019un commentateur est inscrit aux commentaires qui suivre ses commentaires sur un blog post particulaire.\n<\/p>\n<p>Si la personne concern\u00e9e d\u00e9cide d\u2019inscrire \u00e0 cette option, le responsable du traitement enverra un e-mail de confirmation automatique pour v\u00e9rifier via la proc\u00e9dure de double opt-in si le propri\u00e9taire de l&rsquo; e-mail a d\u00e9cid\u00e9 pour cette option. L\u2019option d&rsquo; inscrire aux commentaires peut \u00eatre termin\u00e9e \u00e0 tout moment.<\/p>\n<h4>11. Effacement de routine et blockage des donn\u00e9es \u00e0 caract\u00e8re personnel<\/h4>\n<p>Le responsable du traitement doit proc\u00e9der et conserver les donn\u00e9es \u00e0 caract\u00e8re personnel de la personne concern\u00e9e seulement pendant la p\u00e9riode n\u00e9cessaire pour atteindre la finalit\u00e9 de conservation ou autant que cela est accord\u00e9 par le l\u00e9gislateur europ\u00e9en ou d&rsquo;autres l\u00e9gislateurs dans les lois ou r\u00e8glements auxquels le responsable du traitement est soumis. <\/p>\n<p>Si la finalit\u00e9 de conservation n&rsquo; est pas applicable, ou si la p\u00e9riode de conservation prescrite par le l\u00e9gislateur europ\u00e9en ou un autre l\u00e9gislateur comp\u00e9tent expire, les donn\u00e9es \u00e0 caract\u00e8re personnel sont bloqu\u00e9es ou effac\u00e9es de fa\u00e7on routini\u00e8re conform\u00e9ment aux exigences l\u00e9gales.<\/p>\n<h4>12. Droits de la personne concern\u00e9e<\/h4>\n<ul style=\"list-style: none;\">\n<li>\n<h4>a) Droit de confirmation <\/h4>\n<p>Chaque personne concern\u00e9e a le droit d&rsquo;obtenir du responsable du traitement la confirmation que des donn\u00e9es \u00e0<br \/>\ncaract\u00e8re personnel la concernant sont ou ne sont pas trait\u00e9es. Si la personne concernee veut se pr\u00e9valoir de ce droit de confirmation, la peut \u00e0 tout moment, contacter un employ\u00e9 du responsable du traitement.<\/p>\n<\/li>\n<li>\n<h4>b) Droit d&rsquo;acc\u00e8s<\/h4>\n<p>La personne concern\u00e9e a le droit donn\u00e9 par le l\u00e9gislateur europ\u00e9en d&rsquo; obtenir, \u00e0 tout moment, acc\u00e8s par le responsable du traitement aux informations de ses donn\u00e9es \u00e0 caract\u00e8re personnel conserv\u00e9es et une copie de ces informations. En outre, les directives et r\u00e8glements europ\u00e9ens accordent a la personne concern\u00e9e d&rsquo; acc\u00e8s aux informations suivantes: <\/p>\n<ul style=\"list-style: none;\">\n<li>les finalit\u00e9s du traitement;<\/li>\n<li>les cat\u00e9gories de donn\u00e9es \u00e0 caract\u00e8re personnel concern\u00e9es;<\/li>\n<li>les destinataires ou cat\u00e9gories de destinataires auxquels les donn\u00e9es \u00e0 caract\u00e8re personnel ont \u00e9t\u00e9 ou seront communiqu\u00e9es, en particulier les destinataires qui sont \u00e9tablis dans des pays tiers ou les organisations internationale;<\/li>\n<li>lorsque cela est possible, la dur\u00e9e de conservation des donn\u00e9es \u00e0 caract\u00e8re personnel envisag\u00e9e ou, lorsque ce n&rsquo;est<br \/>\npas possible, les crit\u00e8res utilis\u00e9s pour d\u00e9terminer cette dur\u00e9e;<\/li>\n<li>l&rsquo;existence du droit de demander au responsable du traitement la rectification ou l&rsquo;effacement de donn\u00e9es \u00e0 caract\u00e8re<br \/>\npersonnel, ou une limitation du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel relatives \u00e0 la personne concern\u00e9e, ou<br \/>\ndu droit de s&rsquo;opposer \u00e0 ce traitement;<\/li>\n<li>le droit d&rsquo;introduire une r\u00e9clamation aupr\u00e8s d&rsquo;une autorit\u00e9 de contr\u00f4le;<\/li>\n<li>lorsque les donn\u00e9es \u00e0 caract\u00e8re personnel ne sont pas collect\u00e9es aupr\u00e8s de la personne concern\u00e9e, toute information disponible quant \u00e0 leur source;<\/li>\n<li>l&rsquo;existence d&rsquo;une prise de d\u00e9cision automatis\u00e9e, y compris un profilage, vis\u00e9e \u00e0 l&rsquo;article 22, paragraphes 1 et 4, et, au<br \/>\nmoins en pareils cas, des informations utiles concernant la logique sous-jacente, ainsi que l&rsquo;importance et les<br \/>\ncons\u00e9quences pr\u00e9vues de ce traitement pour la personne concern\u00e9e.<\/li>\n<\/ul>\n<p>En plus, la personne concern\u00e9e a le droit d&rsquo;\u00eatre inform\u00e9e si des donn\u00e9es \u00e0 caract\u00e8re personnel sont transf\u00e9r\u00e9es vers un pays tiers ou \u00e0 une organisation internationale. O\u00f9 c&rsquo;est le cas, la personne concern\u00e9e a le droit d&rsquo;\u00eatre inform\u00e9e des garanties appropri\u00e9es, en ce qui concerne ce transfert.<\/p>\n<p>Si la personne concern\u00e9e veut se pr\u00e9valoir de ce droit d&rsquo;acc\u00e8s, il ou elle peut, \u00e0 tout moment, contacter un employ\u00e9 du responsable du traitement.<\/p>\n<\/li>\n<li>\n<h4>c) Droit de rectification<\/h4>\n<p>La personne concern\u00e9e a le droit accord\u00e9 par le l\u00e9gislateur  europ\u00e9en d&rsquo;obtenir du responsable du traitement, dans les meilleurs d\u00e9lais, la rectification des donn\u00e9es \u00e0 caract\u00e8re personnel la concernant qui sont inexactes. Compte tenu des finalit\u00e9s du traitement, la personne concern\u00e9e a le droit d&rsquo;obtenir que les donn\u00e9es \u00e0 caract\u00e8re personnel incompl\u00e8tes soient compl\u00e9t\u00e9es, y compris en fournissant une d\u00e9claration compl\u00e9mentaire.<\/p>\n<p>Si la personne concern\u00e9e veut exercer ce droit de rectification, il ou elle peut, \u00e0 tout moment, contacter un employ\u00e9 du responsable du traitement. <\/p>\n<\/li>\n<li>\n<h4>d) Droit \u00e0 l&rsquo;effacement (\u00abdroit \u00e0 l&rsquo;oubli\u00bb) <\/h4>\n<p>La personne concern\u00e9e a le droit accord\u00e9 par le l\u00e9gislateur  europ\u00e9en d&rsquo;obtenir du responsable du traitement l&rsquo;effacement, dans les meilleurs d\u00e9lais, de donn\u00e9es \u00e0 caract\u00e8re personnel la concernant et le responsable du traitement a l&rsquo;obligation d&rsquo;effacer ces donn\u00e9es \u00e0 caract\u00e8re personnel dans les meilleurs d\u00e9lais, lorsque l&rsquo;un des motifs suivants s&rsquo;applique:<\/p>\n<ul style=\"list-style: none;\">\n<li>Les donn\u00e9es \u00e0 caract\u00e8re personnel ne sont plus n\u00e9cessaires au regard des finalit\u00e9s pour lesquelles elles ont \u00e9t\u00e9 collect\u00e9es ou trait\u00e9es d&rsquo;une autre mani\u00e8re.<\/li>\n<li>La personne concern\u00e9e retire le consentement sur lequel est fond\u00e9 le traitement, conform\u00e9ment \u00e0 l&rsquo;article 6, paragraphe 1, point a), ou \u00e0 l&rsquo;article 9, paragraphe 2, point a) de RGDP et il n&rsquo;existe pas d&rsquo;autre fondement juridique au traitement.<\/li>\n<li>La personne concern\u00e9e s&rsquo;oppose au traitement en vertu de l&rsquo;article 21, paragraphe 1 de RGPD, et il n&rsquo;existe pas de motif l\u00e9gitime imp\u00e9rieux pour le traitement, ou la personne concern\u00e9e s&rsquo;oppose au traitement en vertu de l&rsquo;article 21, paragraphe 2 de RGPD.<\/li>\n<li>Les donn\u00e9es \u00e0 caract\u00e8re personnel ont fait l&rsquo;objet d&rsquo;un traitement illicite.<\/li>\n<li>Les donn\u00e9es \u00e0 caract\u00e8re personnel doivent \u00eatre effac\u00e9es pour respecter une obligation l\u00e9gale qui est pr\u00e9vue par le droit<br \/>\nde l&rsquo;Union ou par le droit de l&rsquo;\u00c9tat membre auquel le responsable du traitement est soumis.<\/li>\n<li>Les donn\u00e9es \u00e0 caract\u00e8re personnel ont \u00e9t\u00e9 collect\u00e9es dans le cadre de l&rsquo;offre de services de la soci\u00e9t\u00e9 de l&rsquo;information<br \/>\nvis\u00e9e \u00e0 l&rsquo;article 8, paragraphe 1 de RGPD.<\/li>\n<\/ul>\n<p>Si une des raisons susmentionn\u00e9es s&rsquo;applique et la personne concern\u00e9e veut demander l\u2019effacement de donn\u00e9es \u00e0 caract\u00e8re personnel conserv\u00e9es par Cincomedia GmbH, la personne concern\u00e9e peut, \u00e0 tout moment, contacter un employ\u00e9 du responsable du traitement. Un employ\u00e9 de Cincomedia GmbH doit rapidement l&rsquo; assurer que l&rsquo; effacement demand\u00e9 \u00e0 \u00e9t\u00e9 imm\u00e9diatement compl\u00e9t\u00e9.<\/p>\n<p>Lorsque le responsable du traitement a rendu publiques les donn\u00e9es \u00e0 caract\u00e8re personnel et qu&rsquo;il est tenu de les effacer en vertu de l&rsquo;article 17, paragraphe 1, le responsable du traitement, compte tenu des technologies disponibles et des co\u00fbts de mise en \u0153uvre, prend des mesures raisonnables, y compris d&rsquo;ordre technique, pour informer les responsables du traitement qui traitent ces donn\u00e9es \u00e0 caract\u00e8re personnel que la personne concern\u00e9e a demand\u00e9 l&rsquo;effacement par ces responsables du traitement de tout lien vers ces donn\u00e9es \u00e0 caract\u00e8re personnel, ou de toute copie ou reproduction de celles-ci,  autant que le traitement n&rsquo; est pas requis. Un employ\u00e9 de Cincomedia GmbH arrangera les mesures n\u00e9cessaires dans des cas individuels.<\/p>\n<\/li>\n<li>\n<h4>e) Droit \u00e0 la limitation du traitement <\/h4>\n<p>La personne concern\u00e9e a le droit accord\u00e9 par le l\u00e9gislateur europ\u00e9en d&rsquo;obtenir du responsable du traitement la limitation du traitement lorsque l&rsquo;un des \u00e9l\u00e9ments suivants s&rsquo;applique:<\/p>\n<ul style=\"list-style: none;\">\n<li>L&rsquo;exactitude des donn\u00e9es \u00e0 caract\u00e8re personnel est contest\u00e9e par la personne concern\u00e9e, pendant une dur\u00e9e permettant<br \/>\nau responsable du traitement de v\u00e9rifier l&rsquo;exactitude des donn\u00e9es \u00e0 caract\u00e8re personnel. <\/li>\n<li>Le traitement est illicite et la personne concern\u00e9e s&rsquo;oppose \u00e0 leur effacement et exige \u00e0 la place la limitation de leur utilisation.<\/li>\n<li>Le responsable du traitement n&rsquo;a plus besoin des donn\u00e9es \u00e0 caract\u00e8re personnel aux fins du traitement mais celles-ci sont encore n\u00e9cessaires \u00e0 la personne concern\u00e9e pour la constatation, l&rsquo;exercice ou la d\u00e9fense de droits en justice<\/li>\n<li>La personne concern\u00e9e s&rsquo;est oppos\u00e9e au traitement en vertu de l&rsquo;article 21, paragraphe 1 de RGPD pendant la v\u00e9rification portant sur le point de savoir si les motifs l\u00e9gitimes poursuivis par le responsable du traitement pr\u00e9valent sur ceux de la personne concern\u00e9e.<\/li>\n<\/ul>\n<p>Si l&rsquo;un des \u00e9l\u00e9ments suivants s&rsquo;applique et la personne concern\u00e9e veut demander la limitation du traitement de donn\u00e9es \u00e0 caract\u00e8re personnel conserv\u00e9es par Cincomedia GmbH, la personne concern\u00e9e peut, \u00e0 tout moment, contacter un employ\u00e9 du responsable du traitement. Un employ\u00e9 de Cincomedia GmbH organisera la limitation du traitement. <\/p>\n<\/li>\n<li>\n<h4>f) Droit \u00e0 la portabilit\u00e9 des donn\u00e9es <\/h4>\n<p>Les personnes concern\u00e9es ont le droit accord\u00e9 par le l\u00e9gislateur europ\u00e9en de recevoir les donn\u00e9es \u00e0 caract\u00e8re personnel les concernant qu&rsquo;elles ont fournies \u00e0 un responsable du traitement, dans un format structur\u00e9, couramment utilis\u00e9 et lisible par machine. Les personnes concern\u00e9es doivent avoir le droit de transmettre ces donn\u00e9es \u00e0 un autre responsable du traitement sans que le responsable du traitement auquel les donn\u00e9es \u00e0 caract\u00e8re personnel ont \u00e9t\u00e9 communiqu\u00e9es y fasse obstacle, lorsque le traitement est fond\u00e9 sur le consentement en application de l&rsquo;article 6, paragraphe 1, point a), ou de l&rsquo;article 9, paragraphe 2, point a) RGPD, ou sur un contrat en application de l&rsquo;article 6, paragraphe 1, point b) de RGPD, et le traitement est effectu\u00e9 \u00e0 l&rsquo;aide de proc\u00e9d\u00e9s automatis\u00e9s,  si le traitement n&rsquo; est pas n\u00e9cessaire \u00e0 l&rsquo;ex\u00e9cution d&rsquo;une mission d&rsquo;int\u00e9r\u00eat public ou relevant de l&rsquo;exercice de l&rsquo;autorit\u00e9 publique dont est investi le responsable du traitement.<\/p>\n<p>En outre, en exer\u00e7ant le droit \u00e0 la portabilit\u00e9 en application de l&rsquo; article 20, paragraphe 1 de RGPD, la personne concern\u00e9e a<br \/>\nle droit d&rsquo;obtenir que les donn\u00e9es \u00e0 caract\u00e8re personnel soient transmises directement d&rsquo;un responsable du traitement \u00e0 un autre, lorsque cela est techniquement possible et lorsque cela ne porte pas atteinte aux droits et libert\u00e9s d&rsquo;autrui.<\/p>\n<p>Afin de faire valoir le droit \u00e0 la portabilit\u00e9 des donn\u00e9es, la personne concern\u00e9e peut, \u00e0 tout moment, contacter un employ\u00e9 de Cincomedia GmbH.<\/p>\n<\/li>\n<li>\n<h4>g) Droit d&rsquo;opposition <\/h4>\n<p>La personne concern\u00e9e a le droit accord\u00e9 par le l\u00e9gislateur europ\u00e9en de s&rsquo;opposer \u00e0 tout moment, pour des raisons tenant \u00e0 sa situation particuli\u00e8re, \u00e0 un traitement des donn\u00e9es \u00e0 caract\u00e8re personnel la concernant fond\u00e9 sur l&rsquo;article 6, paragraphe 1, point e) ou f) de RGPD. Cela s&rsquo; applique \u00e9galement au profilage fond\u00e9 sur ces dispositions.<\/p>\n<p>Cincomedia GmbH ne traite plus les donn\u00e9es \u00e0 caract\u00e8re personnel, \u00e0 moins qu&rsquo;il ne d\u00e9montre qu&rsquo;il existe des motifs l\u00e9gitimes et imp\u00e9rieux pour le traitement qui pr\u00e9valent sur les int\u00e9r\u00eats et les droits et libert\u00e9s de la personne concern\u00e9e, ou pour la constatation, l&rsquo;exercice ou la d\u00e9fense de droits en justice.<\/p>\n<p>Si Cincomedia GmbH traite les donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 des fins de prospection, la personne concern\u00e9e a le droit<br \/>\nde s&rsquo;opposer \u00e0 tout moment au traitement des donn\u00e9es \u00e0 caract\u00e8re personnel la concernant \u00e0 de telles fins de prospection. Cela s&rsquo; applique \u00e9galement au profilage dans la mesure o\u00f9 il est li\u00e9 \u00e0 une telle prospection. Si la personne concern\u00e9e s&rsquo;oppose au traitement \u00e0 des fins de prospection, les donn\u00e9es \u00e0 caract\u00e8re personnel ne sont plus trait\u00e9es \u00e0 ces fins.<\/p>\n<p>En plus, la personne concern\u00e9e a le droit, pour des raisons tenant \u00e0 sa situation particuli\u00e8re, de s&rsquo; opposer au traitement de donn\u00e9es \u00e0 caract\u00e8re personnel la concernant pas Cincomedia GmbH \u00e0 des fins de recherche scientifique ou historique ou \u00e0 des fins statistiques en application de l&rsquo;article 89, paragraphe 1 de RDPG, sauf si le traitement est n\u00e9cessaire \u00e0 l&rsquo;ex\u00e9cution d&rsquo;une mission d&rsquo;int\u00e9r\u00eat public.<\/p>\n<p>Afin de faire valoir le droit d&rsquo; opposition, la personne concern\u00e9e peut, \u00e0 tout moment, contacter un employ\u00e9 de Cincomedia GmbH. En outre, dans le cadre de l&rsquo;utilisation de services de la soci\u00e9t\u00e9 de l&rsquo;information, et nonobstant la directive 2002\/58\/CE, la personne concern\u00e9e peut exercer son droit d&rsquo;opposition \u00e0 l&rsquo;aide de proc\u00e9d\u00e9s automatis\u00e9s utilisant des sp\u00e9cifications techniques.<\/p>\n<\/li>\n<li>\n<h4>h) D\u00e9cision individuelle automatis\u00e9e et profilage<\/h4>\n<p>La personne concern\u00e9e a le droit accord\u00e9 par le l\u00e9gislateur europ\u00e9en de ne pas faire l&rsquo;objet d&rsquo;une d\u00e9cision fond\u00e9e exclusivement sur un traitement automatis\u00e9, y compris le profilage, produisant des effets juridiques la concernant ou l&rsquo;affectant de mani\u00e8re significative de fa\u00e7on similaire, lorsque la d\u00e9cision (1) n&rsquo; est pas n\u00e9cessaire \u00e0 la conclusion ou \u00e0 l&rsquo;ex\u00e9cution d&rsquo;un contrat entre la personne concern\u00e9e et un responsable du traitement, ou (2) n&rsquo; est pas autoris\u00e9e par le droit de l&rsquo;Union ou le droit de l&rsquo;\u00c9tat membre auquel le responsable du traitement est soumis et qui pr\u00e9voit \u00e9galement des mesures appropri\u00e9es pour la sauvegarde des droits et libert\u00e9s et des int\u00e9r\u00eats l\u00e9gitimes de la personne concern\u00e9e, ou (3) n&rsquo; est pas fond\u00e9e sur le consentement explicite de la personne concern\u00e9e. <\/p>\n<p>Si la d\u00e9cision (1) est n\u00e9cessaire \u00e0 la conclusion ou \u00e0 l&rsquo;ex\u00e9cution d&rsquo;un contrat entre la personne concern\u00e9e et un responsable du<br \/>\ntraitement, ou (2) est fond\u00e9e sur le consentement explicite de la personne concern\u00e9e, Cincomedia GmbH met en \u0153uvre des mesures appropri\u00e9es pour la sauvegarde des droits et libert\u00e9s et des int\u00e9r\u00eats l\u00e9gitimes de la personne concern\u00e9e, au moins du<br \/>\ndroit d&rsquo;obtenir une intervention humaine de la part du responsable du traitement, d&rsquo;exprimer son point de vue et de contester la d\u00e9cision.<\/p>\n<p>Si la personne concern\u00e9e veut exercer les droits relatifs \u00e0 la prise de d\u00e9cision individuelle automatis\u00e9e, elle peut \u00e0 tout moment contacter un employ\u00e9 du Cincomedia GmbH.<\/p>\n<\/li>\n<li>\n<h4>i) Droit de retirer de consentement au traitement<\/h4>\n<p>La personne concern\u00e9e a le droit accord\u00e9 par le l\u00e9gislateur europ\u00e9en de retirer son consentement au traitement de ses donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 tout moment.<\/p>\n<p>Si la personne concern\u00e9e veut exercer le droit de retirer de consentement, elle peut \u00e0 tout moment contacter un employ\u00e9 du Cincomedia GmbH.<\/p>\n<\/li>\n<\/ul>\n<h4>13. Dispositions relatives \u00e0 la protection des donn\u00e9es concernant l\u2019application et l\u2019utilisation de Facebook<\/h4>\n<p>Sur ce site Web, le responsable du traitement a int\u00e9gr\u00e9 des composants de l&rsquo;entreprise Facebook. Facebook est un r\u00e9seau  social.<\/p>\n<p>Un r\u00e9seau social est un lieu de rencontres sociales sur Internet, une communaut\u00e9 en ligne qui permet aux utilisateurs de communiquer entre eux et d&rsquo;interagir dans un espace virtuel. Un r\u00e9seau social peut servir comme un plate-forme pour l&rsquo;\u00e9change d&rsquo;opinions et d&rsquo;exp\u00e9riences ou permet \u00e0 la communaut\u00e9 Internet de fournir des informations personnelles ou professionnelles. Facebook permet aux utilisateurs de r\u00e9seaux sociaux d&rsquo; inclure la cr\u00e9ation des profils priv\u00e9s, de t\u00e9l\u00e9charger des photos et de cr\u00e9er des r\u00e9seaux via des demandes d&rsquo;amis.<\/p>\n<p>L&rsquo; entreprise d&rsquo; exploitation de Facebook est Facebook, Inc., 1 Hacker Way, Menlo Park, CA 94025, United States. Pour des personnes qui vivent en dehors des \u00c9tats-Unis, le responsable du traitement est Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Ireland.<\/p>\n<p>En appelant une des pages individuelles de ce site Web qui est exploit\u00e9e par le responsable du traitement et sur laquelle a \u00e9t\u00e9 int\u00e9gr\u00e9 un composant de Facebook (Facebook plug-in), le navigateur Internet sur le syst\u00e8me informatique de la personne concern\u00e9e est automatiquement invit\u00e9 par la composant Facebook \u00e0 t\u00e9l\u00e9charger l&rsquo;affichage du composant Facebook via le composant Facebook. Une view d&rsquo; ensemble de tous les plug-ins Facebook est accessible sous https:\/\/developers.facebook.com\/docs\/plugins\/. Pendant cette proc\u00e9dure technique, Facebook reconnais les sous-sites sp\u00e9cifiques de notre site Web que la personne concern\u00e9e a visit\u00e9.<\/p>\n<p>Si la personne concern\u00e9e est en m\u00eame temps connect\u00e9e sur Facebook, Facebook d\u00e9tecte en appelant notre site Web par la personne concern\u00e9e &#8211; et pour toute la dur\u00e9e de leur visite sur notre site Internet &#8211; quel sous-site sp\u00e9cifique de notre site Web a \u00e9t\u00e9 visit\u00e9 par la personne concern\u00e9e. Ces informations sont collect\u00e9es via la composant Facebook et associ\u00e9es au compte Facebook respectif de la personne concern\u00e9e. Si la personne concern\u00e9e clique sur l&rsquo;un des boutons Facebook int\u00e9gr\u00e9s \u00e0 notre site Web, par exemple le bouton \u00ab\u00a0Like\u00a0\u00bb, or si la personne concern\u00e9e soumet un commentaire, dont Facebook associe ces informations au compte personnel Facebook de la personne concern\u00e9e et conserves les donn\u00e9es \u00e0 caract\u00e8re personnel.<\/p>\n<p>Facebook re\u00e7oit toujours via le composant Facebook des informations sur la visite sur notre site Web par la personne concern\u00e9e, chaque fois que la personne concern\u00e9e est connect\u00e9e en m\u00eame temps sur Facebook pendant l&rsquo; appel sur notre site Web. Cela a lieu ind\u00e9pendamment du fait que la personne concern\u00e9e clique ou ne clique pas sur le composant Facebook. Si une telle transmission d&rsquo; information vers Facebook n&rsquo;est pas souhait\u00e9e par la personne concern\u00e9e,  il ou elle peut emp\u00eacher cela en se d\u00e9connectant du compte Facebook avant l&rsquo;appel sur notre site Web.<\/p>\n<p>La directive sur la protection des donn\u00e9es publi\u00e9e par Facebook, qui est disponible sur https:\/\/facebook.com\/about\/privacy\/, offre des information pour la collecte, le traitement et l&rsquo; utilisation des donn\u00e9es \u00e0 caract\u00e8re personnel par Facebook. En outre, ils sont ici expliqu\u00e9s les options de r\u00e9glage qui Facebook offre pour prot\u00e9ger la confidentialit\u00e9 de la personne concern\u00e9e Des options de configuration diff\u00e9rentes sont \u00e9galement disponibles pour permettre l&rsquo; \u00e9limination des transmissions des donn\u00e9es  vers Facebook. Ces applications peuvent \u00eatre utilis\u00e9es par la personne concern\u00e9e pour \u00e9liminer une transmission des donn\u00e9es vers  Facebook.<\/p>\n<h4>14. Dispositions relatives \u00e0 la protection des donn\u00e9es concernant l\u2019application et l\u2019utilisation de Google Analytics (avec fonction d&rsquo;anonymisation)<\/h4>\n<p>Sur ce site Web, le responsable du traitement a int\u00e9gr\u00e9 des composants de Google Analytics (avec fonction d&rsquo;anonymisation). Google Analytics est un service d&rsquo; analyse Web.L&rsquo; analyse Web est la collecte et analyse des donn\u00e9es sur le comportement des visiteurs des sites Web. Un service d&rsquo; analyse Web capture, entre autres, des donn\u00e9es pertinentes aux quel site Web une personne est arriv\u00e9e via un autre site Web (le soi-disant referrer), quel sous-site du site Web a \u00e9t\u00e9 visit\u00e9 ou \u00e0 quelle fr\u00e9quence et pour quelle dur\u00e9e ce sous-site a \u00e9t\u00e9 vu. L&rsquo;analyse Web est principalement utilis\u00e9e pour l&rsquo; optimisation d&rsquo; un site Web afin d&rsquo;effectuer une analyse co\u00fbts-avantages de la publicit\u00e9 sur Internet.<\/p>\n<p>L&rsquo; entreprise d&rsquo; exploitation du composant de Google Ireland Limited, Gordon House, Barrow Street, Dublin, D04 E5W5, Ireland.<\/p>\n<p>Pour l&rsquo; analyse Web via Google Analytics le responsable du traitement utilise l&rsquo;application \u00ab\u00a0_gat. _anonymizeIp\u00a0\u00bb. Au moyen de cette application, l&rsquo;adresse IP de la connexion Internet de la personne concern\u00e9e est abr\u00e9g\u00e9e par Google et anonymis\u00e9e lors de l&rsquo;acc\u00e8s \u00e0 nos sites Web \u00e0 partir d&rsquo;un \u00c9tat membre de l&rsquo;Union europ\u00e9enne ou d&rsquo;un autre \u00c9tat contractant \u00e0 l&rsquo;accord sur l&rsquo;Espace \u00e9conomique europ\u00e9en. <\/p>\n<p>La finalit\u00e9 du composant de Google Analytics est d&rsquo; analyser le trafic sur notre site Web. Google utilise les donn\u00e9es et information collect\u00e9es, entre autres, pour \u00e9valuer l&rsquo;utilisation de notre site Web et fournir des rapports en ligne, qui montrent les activit\u00e9s de nos sites Web, et \u00e0 fournir d\u2019autres services relatifs \u00e0 l&rsquo;utilisation de notre site Web pour nous.<\/p>\n<p>Google Analytics place un cookie sur le syst\u00e8me informatique de la personne concern\u00e9e. La d\u00e9finition des cookies est expliqu\u00e9e ci-dessus. De cette fa\u00e7on, Google peut analyser l&rsquo;utilisation de notre site Web. En appelant une des pages individuelles de ce site Web qui est exploit\u00e9e par le responsable du traitement et sur laquelle a \u00e9t\u00e9 int\u00e9gr\u00e9 un composant de Google Analytics, le navigateur Internet sur le syst\u00e8me informatique de la personne concern\u00e9e soumettra automatiquement des donn\u00e9es via le composant Google Analytics pour la publicit\u00e9 en ligne et le r\u00e8glement de commissions \u00e0 Google. Dans le cadre de cette proc\u00e9dure technique, l&rsquo;entreprise Google est inform\u00e9 pour des donn\u00e9es \u00e0 caract\u00e8re personnel, comme l&rsquo; adresse IP de la personne concern\u00e9e, qui permet \u00e0 Google, entre autres, de comprendre l&rsquo;origine des visiteurs et clics, et alors de cr\u00e9er des r\u00e8glements de commissions.\n<\/p>\n<p>Le cookie est utilis\u00e9 pour conserver des donn\u00e9es \u00e0 caract\u00e8re personnel, comme l&rsquo;heure d&rsquo;acc\u00e8s, la location \u00e0 partir de laquelle l&rsquo;acc\u00e8s a \u00e9t\u00e9 effectu\u00e9 et la fr\u00e9quence des visites de notre site Web par la personne concern\u00e9e. \u00c0 chaque visite sur notre site web, telles donn\u00e9es \u00e0 caract\u00e8re personnel, y compris l\u2019adresse IP de l\u2019acc\u00e8s Internet utilis\u00e9 par la personne concern\u00e9e, seront transmises \u00e0 Google aux \u00c9tats-Unis. Ces donn\u00e9es \u00e0 caract\u00e8re personnel sont conserv\u00e9es par Google aux \u00c9tats-Unis. Google peut divulguer les donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es par le biais de cette proc\u00e9dure technique \u00e0 des tiers.<\/p>\n<p>Comme indiqu\u00e9 ci-dessus, la personne concern\u00e9e peut, \u00e0 tout moment, emp\u00eacher le placement des cookies via notre site Web en faisant un r\u00e9glage  correspondant sur le navigateur Internet utilis\u00e9 et, de cette fa\u00e7on, nier en permanence le r\u00e9glage des cookies. Un tel r\u00e9glage du navigateur Internet utilis\u00e9 emp\u00eacher Google Analytics de placer un cookie sur le syst\u00e8me informatique de la personne concern\u00e9e. Les cookies d\u00e9j\u00e0 utilis\u00e9s par Google Analytics peuvent \u00eatre \u00e9galement, \u00e0  tout moment, effac\u00e9s via un navigateur Internet ou d&rsquo; autre logiciel.<\/p>\n<p>La personne concern\u00e9e a aussi la possibilit\u00e9 de s\u2019opposer \u00e0 la collecte des donn\u00e9es g\u00e9n\u00e9r\u00e9es concernant l&rsquo;utilisation de ce site Web par Google Analytics, ainsi que le traitement de ces donn\u00e9es par Google, et la et la chance d&#8217;emp\u00eacher un tel traitement.  \u00c0 cette fin, la personne doit t\u00e9l\u00e9charger un add-on de navigateur sous le lien https:\/\/tools.google.com\/dlpage\/gaoptout et l&rsquo; installer. Cet add-on de navigateur informe Google Analytics via JavaScript que toutes les donn\u00e9es et information relatives aux visites de pages Internet ne peuvent pas \u00eatre transmises \u00e0 Google Analytics. L\u2019installation d&rsquo;add-n de navigateur est consid\u00e9r\u00e9e comme une objection vers Google. Si le syst\u00e8me informatique de la personne concern\u00e9e est ult\u00e9rieurement supprim\u00e9, format\u00e9 ou nouvellement install\u00e9, la personne concern\u00e9e doit alors r\u00e9installer les add-ons de navigateur pour d\u00e9sactiver Google Analytics. Si l&rsquo;add-on de navigateur a \u00e9t\u00e9 d\u00e9sinstalle par la personne concern\u00e9e ou par d&rsquo;autre personne comp\u00e9tente ou c&rsquo;est d\u00e9sactiv\u00e9, il est possible d&rsquo;ex\u00e9cuter la r\u00e9installation ou la r\u00e9activation des add-ons de navigateur.<\/p>\n<p>Des informations suppl\u00e9mentaires et les dispositions applicables de Google sous https:\/\/www.google.com\/intl\/en\/policies\/privacy\/ and under http:\/\/www.google.com\/analytics\/terms\/us.html. Google Analytics est expliqu\u00e9 sous le lien https:\/\/www.google.com\/analytics\/.<\/p>\n<h4>15. Dispositions relatives \u00e0 la protection des donn\u00e9es concernant l\u2019application et l\u2019utilisation de Google+<\/h4>\n<p>Sur ce site Web, le responsable du traitement a int\u00e9gr\u00e9 le bouton Google+. Google+ est un soi-disant r\u00e9seau social. Un r\u00e9seau social est un lieu de rencontres sociales sur Internet, une communaut\u00e9 en ligne qui permet aux utilisateurs de communiquer entre eux et d&rsquo;interagir dans un espace virtuel. Un r\u00e9seau social peut servir comme un plate-forme pour l&rsquo;\u00e9change d&rsquo;opinions et d&rsquo;exp\u00e9riences ou permet \u00e0 la communaut\u00e9 Internet de fournir des informations personnelles ou professionnelles. Google+ permet aux utilisateurs de r\u00e9seau sociaux d\u2019inclure la cr\u00e9ation des profils priv\u00e9s, de t\u00e9l\u00e9charger des photos et de cr\u00e9er des r\u00e9seaux via des demandes d&rsquo;amis.<\/p>\n<p>L&rsquo; entreprise d&rsquo; exploitation de Google+ est Google Ireland Limited, Gordon House, Barrow Street, Dublin, D04 E5W5, Ireland.<\/p>\n<p>En appelant une des pages individuelles de ce site Web qui est exploit\u00e9e par le responsable du traitement et sur laquelle a \u00e9t\u00e9 int\u00e9gr\u00e9 un composant d&rsquo; Google+, le navigateur Internet de la personne concern\u00e9e t\u00e9l\u00e9charge automatiquement un affichage  du bouton Google+ via le composant de bouton Google+ correspondant. Pendant cette proc\u00e9dure technique, Google est inform\u00e9 des sous-sites individuels sp\u00e9cifiques de ce site Web que la personne concern\u00e9e a visit\u00e9. Des informations plus d\u00e9taill\u00e9es sur Google+ sont disponibles sous https:\/\/developers.google.com\/+\/.<\/p>\n<p>Si la personne concern\u00e9e est en m\u00eame temps connect\u00e9e sur Google+, Google+ d\u00e9tecte en appelant notre site Web par la personne concern\u00e9e &#8211; et pour toute la dur\u00e9e de leur visite sur notre site Internet &#8211; quel sous-site sp\u00e9cifique de notre site Web a \u00e9t\u00e9 visit\u00e9 par la personne concern\u00e9e. Ces informations sont collect\u00e9es via le bouton Google+ et associ\u00e9es au compte Google+ respectif de la personne concern\u00e9e. <\/p>\n<p>Si la personne concern\u00e9e clique sur le bouton Google+ int\u00e9gr\u00e9 \u00e0 notre site Web Google+ et donne une recommandation, dont Google associe ces informations au compte personnel Google+ de la personne concern\u00e9e et conserve les donn\u00e9es \u00e0 caract\u00e8re personnel. Google conserve la recommandation Google+ 1 de la personne concern\u00e9e et rendre-la accessible au public conform\u00e9ment aux conditions g\u00e9n\u00e9rales accept\u00e9es par la personne concern\u00e9e \u00e0 cet \u00e9gard. Une recommandation Google+ 1 par la personne concern\u00e9e sur ce site Web avec d&rsquo;autres donn\u00e9es \u00e0 caract\u00e8re personnel, par exemple le nom du compte Google+ utilise par la personne concern\u00e9e et la photo enregistr\u00e9e, sont conserves et traites par les autres services, comme les r\u00e9sultats  du moteur de recherche Google, le compte Google de la personne concern\u00e9e ou aux autres sites, par exemple sur des sites Internet, ou par rapport aux publicit\u00e9s. Google peut aussi lier la visite sur ce site Web aux autres donn\u00e9es \u00e0 caract\u00e8re personnel conserv\u00e9es par Google. Google enregistre ces information dans le but d&rsquo;am\u00e9liorer ou d&rsquo;optimiser les services Google.<\/p>\n<p>Google re\u00e7oit l&rsquo;information par le bouton Google+ que la personne concern\u00e9e a visite notre site Web, si la personne concern\u00e9e est en m\u00eame temps connect\u00e9e sur Google+. Cela se produit ind\u00e9pendamment du fait que la personne concern\u00e9e clique ou ne clique pas sur le bouton Google+.<\/p>\n<p>Si la personne concern\u00e9e ne souhaite pas la transmission des donn\u00e9es \u00e0 caract\u00e8re personnel sur Google, cela peut emp\u00eacher une telle transmission en d\u00e9connectant de son compte Google+ avant d&rsquo;appeler notre site Web.<\/p>\n<p>Des informations suppl\u00e9mentaires et les dispositions applicables de Google sous https:\/\/www.google.com\/intl\/en\/policies\/privacy\/. Plus de r\u00e9f\u00e9rences de Google pour le bouton Google+ 1 peuvent \u00eatre obtenues sous https:\/\/developers.google.com\/+\/web\/buttons-policy.<\/p>\n<h4>16. Dispositions relatives \u00e0 la protection des donn\u00e9es concernant l\u2019application et l\u2019utilisation d&rsquo; Instagram<\/h4>\n<p>Sur ce site Web, le responsable du traitement a int\u00e9gr\u00e9 des composants d&rsquo; Instagram. Instagram est un service pouvant \u00eatre qualifi\u00e9 de plateforme audiovisuelle, qui permet aux utilisateurs de partager des photos et des vid\u00e9os, ainsi que diffuser ces donn\u00e9es dans d&rsquo;autres r\u00e9seaux sociaux.<\/p>\n<p>L&rsquo; entreprise d&rsquo; exploitation des services offerts par Instagram est Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2 Ireland.<\/p>\n<p>En appelant une des pages individuelles de ce site Web qui est exploit\u00e9e par le responsable du traitement et sur laquelle a \u00e9t\u00e9 int\u00e9gr\u00e9 un composant d&rsquo; Instagram (le bouton Insta), le navigateur Internet de la personne concern\u00e9e t\u00e9l\u00e9charge automatiquement un affichage du composant Instagram via le composant respectif Instagram. Pendant cette proc\u00e9dure technique, Instagram des sous-sites individuelles sp\u00e9cifiques de ce site Web que la personne concern\u00e9e a visit\u00e9.<\/p>\n<p>Si la personne concern\u00e9e est en m\u00eame temps connect\u00e9e sur Instagram, Instagram d\u00e9tecte en appelant notre site Web par la personne concern\u00e9e &#8211; et pour toute la dur\u00e9e de leur visite sur notre site Internet &#8211; quel sous-site sp\u00e9cifique de notre site Web a \u00e9t\u00e9 visit\u00e9 par la personne concern\u00e9e. Ces informations sont collect\u00e9es via le composant Instagram, et associ\u00e9es au compte Google+ respectif de la personne concern\u00e9e. Si la personne concern\u00e9e clique sur un des boutons Instagram int\u00e8gres sur notre site Web, Instagram associe ces informations avec le compte d&rsquo;utilisateur Instagram personnel de la personne concern\u00e9e et recorde les donn\u00e9es personnelles.<\/p>\n<p>Instagram re\u00e7oit l&rsquo;information par le composant Instagram que la personne concern\u00e9e a visite notre site Web, si la personne concern\u00e9e est en m\u00eame temps connect\u00e9e sur Instagram. Cela se produit ind\u00e9pendamment du fait que la personne concern\u00e9e clique ou ne clique pas sur le bouton Instagram. Si une telle transmission d&rsquo;information vers Instagram n&rsquo;est pas souhaitable par la personne concern\u00e9e, la personne concernee peut l&#8217;emp\u00eacher en se d\u00e9connectant de on compte Instagram avant d&rsquo; appeler notre site Web. <\/p>\n<p>Des informations suppl\u00e9mentaires et les dispositions applicables d&rsquo; Instagram sous https:\/\/help.instagram.com\/155833707900388 and https:\/\/www.instagram.com\/about\/legal\/privacy\/.<\/p>\n<h4>17. Dispositions relatives \u00e0 la protection des donn\u00e9es concernant l\u2019application et l\u2019utilisation de Jetpack pour WordPress<\/h4>\n<p>Sur ce site Web, le responsable du traitement a int\u00e9gr\u00e9 Jetpack. Jetpack est un plug-in de WordPress, which offre des fonctions suppl\u00e9mentaires \u00e0 l&rsquo;operateur d&rsquo; un site Web bas\u00e9 sur WordPres. Jetpack permet a l&rsquo; operateur d&rsquo;un site Web, entre autres, un image des visiteurs de ce cite Web. En affichant des publications relatives ou avec la possibilit\u00e9 de partager du contenu sur la page, il est \u00e9galement possible d&rsquo;augmenter le nombre des visiteurs. En outre, des fonctions de s\u00e9curit\u00e9 sont int\u00e9gr\u00e9es sur Jetpack, donc un site utilisant Jetpack est mieux prot\u00e9g\u00e9 contre les attaques de force-brute. Jetpack alors optimise et acc\u00e9l\u00e8re le chargement des images sur le site.<\/p>\n<p>L&rsquo; entreprise d&rsquo; exploitation de Jetpack Plug-Ins pour WordPress est Aut O\u2019Mattic A8C Ireland Ltd., Business Centre, No.1 Lower Mayor Street, International Financial Services Centre, Dublin 1, Ireland.<\/p>\n<p>Jetpack place un cookie sur le syst\u00e8me informatique de la personne concern\u00e9e. La d\u00e9finition des cookies est expliqu\u00e9e ci-dessus. En appelant l&rsquo; une des pages individuelles de ce site Web qui est exploit\u00e9e par le responsable du traitement et sur laquelle a \u00e9t\u00e9 int\u00e9gr\u00e9 un composant de Jetpack, le navigateur Internet de la personne concern\u00e9e est automatiquement invit\u00e9 de soumettre des donn\u00e9es au moyen de composant de Jetpack vers Automattic. Dans le cadre de cette proc\u00e9dure technique Automattic re\u00e7oit des donn\u00e9es qui sont utilis\u00e9es pour cr\u00e9er un aper\u00e7u des visites sur le site Web. Les donn\u00e9es obtenues de cette fa\u00e7on servent \u00e0 l&rsquo;analyse du comportement de la personne concern\u00e9e, qui acc\u00e8de au site Web du responsable du traitement, et ils sont analys\u00e9s pour l&rsquo;optimisation de ce site Web. Les donn\u00e9es collect\u00e9es via le composant Jetpack ne sont pas utilis\u00e9es pour identifier la personne concern\u00e9e sans son consentement distinct et explicite au pr\u00e9alable. Les donn\u00e9es viennent \u00e0 la connaissance de Quantcast. Quantcast utilise les donn\u00e9es aux m\u00eames fins que Automattic.<\/p>\n<p>Comme indiqu\u00e9 ci-dessus, La personne concern\u00e9e peut, \u00e0 tout moment, emp\u00eacher le placement des cookies via notre site Web en faisant un r\u00e9glage correspondant sur le navigateur Internet utilis\u00e9 et, de cette fa\u00e7on, nier en permanence le r\u00e9glage des cookies. Un tel r\u00e9glage du navigateur Internet utilis\u00e9 emp\u00eacher Automattic\/Quantcast de placer un cookie sur le syst\u00e8me informatique de la personne concern\u00e9e. Les cookies d\u00e9j\u00e0 utilis\u00e9s par Automattic\/Quantcast peuvent \u00eatre \u00e9galement, \u00e0  tout moment, effac\u00e9s via un navigateur Internet ou d&rsquo; autre logiciel. <\/p>\n<p>La personne concern\u00e9e a aussi la possibilit\u00e9 de s\u2019opposer \u00e0 la collection des donn\u00e9es relatives \u00e0 l&rsquo;utilisation de ce site Internet  g\u00e9n\u00e9r\u00e9es par le cookie Jetpack ainsi qu&rsquo; au traitement de ces donn\u00e9es par Automattic\/Quantcast et il a le chance d&#8217;emp\u00eacher une telle collection. \u00c0 cette fin, la personne concern\u00e9e doit cliquer sur le bouton de d\u00e9sinscription (opt-out) sous le lien Web https:\/\/www.quantcast.com\/opt-out\/ qui place un opt-out cookie. L&rsquo;opt-out cookie utilis\u00e9 de cette raison est plac\u00e9 sur le syst\u00e8me informatique utilis\u00e9 par la personne concern\u00e9e. Si la personne concern\u00e9e efface les cookies de son syst\u00e8me, la personne concern\u00e9e doit alors rappeler le lien et placer un nouveau opt-out cookie.<\/p>\n<p>En pla\u00e7ant l&rsquo; opt-out cookie, il y a cependant la possibilit\u00e9 que les sites Web du responsable du traitement ne soient pas enti\u00e8rement utilisables par la personne concern\u00e9e. <\/p>\n<p>Les dispositions de protection des donn\u00e9es applicables par Automattic sont accessibles sous https:\/\/automattic.com\/privacy\/. Les dispositions de protection des donn\u00e9es applicables par Quantcast sont accessibles sous https:\/\/www.quantcast.com\/privacy\/.<\/p>\n<h4>18. Dispositions relatives \u00e0 la protection des donn\u00e9es concernant l\u2019application et l\u2019utilisation de LinkedIn<\/h4>\n<p>Sur ce site Web, le responsable du traitement a int\u00e9gr\u00e9 des composants de LinkedIn Corporation. LinkedIn est un r\u00e9seau social sur Web qui permet aux utilisateurs avec des contacts professionnels existants de se connecter et de faire de nouveaux professionnels. Plus de 400 million de personnes enregistr\u00e9es dans plus de 200 pays utilisent LinkedIn. LinkedIn est alors la plateforme la plus grande des contacts professionnelles et l&rsquo;un des sites Web les plus visit\u00e9s du monde.<\/p>\n<p>L\u2019entreprise d&rsquo; exploitation de LinkedIn est LinkedIn Corporation, 2029 Stierlin Court Mountain View, CA 94043, UNITED STATES. Pour les questions de confidentialit\u00e9 en dehors des \u00c9tats-Unis est LinkedIn Ireland, Privacy Policy Issues, Wilton Plaza, Wilton Place, Dublin 2, Ireland, est responsable.<\/p>\n<p>En appelant l&rsquo;une des pages individuelles de ce site Web qui est exploit\u00e9e par le responsable du traitement et sur laquelle a \u00e9t\u00e9 int\u00e9gr\u00e9 un composant de LinkedIn (LinkedIn plug-in), le navigateur Internet sur le syst\u00e8me informatique de la personne concern\u00e9e est automatiquement invit\u00e9 \u00e0 t\u00e9l\u00e9charger une affiche du composant LinkedIn.  Des Informations compl\u00e9mentaires sur LinkedIn plug-in sont accessibles sous https:\/\/developer.linkedin.com\/plugins. En course de cette proc\u00e9dure technique LinkedIn est inform\u00e9 de quel sous-site sp\u00e9cifique de notre site Web a \u00e9t\u00e9 visit\u00e9 par la personne concern\u00e9e.<\/p>\n<p>Si la personne concern\u00e9e est en m\u00eame temps connect\u00e9e sur LinkedIn, d\u00e9tecte en appelant notre site Web par la personne concern\u00e9e &#8211; et pour toute la dur\u00e9e de leur visite sur notre site Internet &#8211; quel sous-site sp\u00e9cifique de notre site Web a \u00e9t\u00e9 visit\u00e9 par la personne concern\u00e9e. Ces informations sont collect\u00e9es via la composant LinkedIn et associ\u00e9es au compte LinkedIn respectif de la personne concern\u00e9e.. Si la personne concern\u00e9e clique sur l&rsquo;un des boutons LinkedIn int\u00e9gr\u00e9s \u00e0 notre site Web, dont LinkedIn associe ces informations au compte personnel LinkedIn de la personne concern\u00e9e et conserves les donn\u00e9es \u00e0 caract\u00e8re personnel.<\/p>\n<p>LinkedIn re\u00e7oit l&rsquo;information par le composant LinkedIn que la personne concern\u00e9e a visite notre site Web, si la personne concern\u00e9e est en m\u00eame temps connect\u00e9e sur LinkedIn. Cela se produit ind\u00e9pendamment du fait que la personne concern\u00e9e clique ou ne clique pas sur le bouton LinkedIn. Si une telle transmission d&rsquo;information vers Instagram n&rsquo;est pas souhaitable par la personne concern\u00e9e, la personne concern\u00e9e peut l&#8217;emp\u00eacher en se d\u00e9connectant de on compte Instagram avant d&rsquo; appeler notre site Web.  <\/p>\n<p>LinkedIn offre la possibilite de se d\u00e9sabonner des messages e-mail, SMS et des annonces cibl\u00e9es, ainsi que de la possibilit\u00e9 de g\u00e9rer les param\u00e8tres des annonces sous https:\/\/www.linkedin.com\/psettings\/guest-controls. LinkedIn utilise aussi des entreprises filiales comme  Eire, Google Analytics, BlueKai, DoubleClick, Nielsen, Comscore, Eloqua, et Lotame. La configuration de ces cookies peut \u00eatre refus\u00e9e sous https:\/\/www.linkedin.com\/legal\/cookie-policy. La politique de confidentialit\u00e9 applicable \u00e0 LinkedIn est disponible sous https:\/\/www.linkedin.com\/legal\/privacy-policy. La politique de cookie de LinkedIn est disponible sous https:\/\/www.linkedin.com\/legal\/cookie-policy.<\/p>\n<h4>19. Dispositions relatives \u00e0 la protection des donn\u00e9es concernant l\u2019application et l\u2019utilisation de Twitter<\/h4>\n<p>Sur ce site Web, le responsable du traitement a int\u00e9gr\u00e9 des composants de Twitter. Twitter est un service demicrobloging multilingue et accessible au public sur lequel les utilisateurs peuvent publier et diffuser des soi-disant \u00ab\u00a0tweets\u00a0\u00bb, par exemple des messages courts, qui sont limit\u00e9s \u00e0 280 caract\u00e8res. Ces messages courts sont disponibles a tous, y compris ceux qui ne sont pas connect\u00e9s sur Twitter. Ces tweets sont aussi affich\u00e9s aux followers de l&rsquo;utilisateur respectif. Les followers sont d&rsquo;autres utilisateurs de Twitter qui suivent des tweets d&rsquo;autres utilisateurs. En outre, Twitter permet de s&rsquo;adresser \u00e0 un large public via hashtags (mot-di\u00e8se), liens ou re-tweets.<\/p>\n<p>L&rsquo; entreprise d&rsquo; exploitation de Twitter est Twitter International Company, One Cumberland Place, Fenian Street Dublin 2, D02 AX07, Ireland.<\/p>\n<p>En appelant l\u2019une des pages individuelles de ce site Web qui est exploit\u00e9e par le responsable du traitement et sur laquelle a \u00e9t\u00e9 int\u00e9gr\u00e9 un composant de Twitter (le bouton Twitter), le navigateur Internet de la personne concern\u00e9e est automatiquement invit\u00e9 \u00e0 t\u00e9l\u00e9charger une affiche du composant de Twitter. En savoir plus sur le bouton Twitter sous https:\/\/about.twitter.com\/de\/resources\/buttons. En course de cette proc\u00e9dure technique, Twitter est informe de sous-site sp\u00e9cifique de notre site Web visit\u00e9 par la personne concern\u00e9e. Le but de l&rsquo;int\u00e9gration du composant Twitter est une retransmission du contenu de ce site Web pour permettre \u00e0 nos utilisateurs de pr\u00e9senter cette page Web au monde num\u00e9rique et d&rsquo;augmenter le nombre de visiteurs.<\/p>\n<p>Si la personne concern\u00e9e est en m\u00eame temps connect\u00e9e sur Twitter, Twitter d\u00e9tecte en appelant notre site Web par la personne concern\u00e9e &#8211; et pour toute la dur\u00e9e de leur visite sur notre site Internet &#8211; quel sous-site sp\u00e9cifique de notre site Web a \u00e9t\u00e9 visit\u00e9 par la personne concern\u00e9e. Ces informations sont collect\u00e9es via la composant Twitter et associ\u00e9es au compte Twitter respectif de la personne concern\u00e9e. Si la personne concern\u00e9e clique sur l&rsquo;un des boutons Twitter int\u00e9gr\u00e9s \u00e0 notre site Web, dont Twitter associe ces informations au compte personnel Twitter de la personne concern\u00e9e et conserves les donn\u00e9es \u00e0 caract\u00e8re personnel.<\/p>\n<p>Twitter re\u00e7oit via le composant Twitter l&rsquo;information que la personne concern\u00e9e a visit\u00e9 notre site Web, si la personne concern\u00e9e est en meme temps connect\u00e9e sur Twitter. Cela se produit ind\u00e9pendamment du fait que la personne concern\u00e9e clique ou ne clique pas sur les m\u00e9dias int\u00e9gr\u00e9s. Si la personne concern\u00e9e ne souhaite pas la transmission des informations sur Twitter, il peut emp\u00eacher une telle transmission en d\u00e9connectant de son compte Twitter avant d&rsquo;appeler notre site Web.<\/p>\n<p>Les dispositions de protection des donn\u00e9es applicables par Twitter sont disponibles sous https:\/\/twitter.com\/privacy?lang=en.<\/p>\n<h4>20. Mode de paiement: Dispositions relatives \u00e0 la protection des donn\u00e9es concernant l&rsquo;utilisation de Klarna comme processeur de paiement<\/h4>\n<p>Sur ce site Web, le responsable du traitement a int\u00e9gr\u00e9 des composants de Klarna. Klarna est un fournisseur de service de paiement en ligne, qui permet des achats sur un compte ou des paiements flexibles par acomptes. Klarna offre \u00e9galement d&rsquo;autres services, comme protection de l&rsquo;acheteur et contr\u00f4les d&rsquo;identit\u00e9 ou de solvabilit\u00e9.<\/p>\n<p>L&rsquo; entreprise d&rsquo; exploitation de Klarna Bank AB, Sveav\u00e4gen 46, 111 34 Stockholm, Schweden.<\/p>\n<p>Si la personne concern\u00e9e choisit l&rsquo; \u00ab\u00a0\u00a0\u00bbachat sur compte\u00a0\u00bb\u00a0\u00bb ou \u00ab\u00a0\u00a0\u00bbachat avec acomptes\u00a0\u00bb\u00a0\u00bb pendant du processus de commande dans notre boutique en ligne comme une option de paiement, les donn\u00e9es de la personne concern\u00e9e sont automatiquement transmises \u00e0 Klarna. En choisissant l&rsquo;une de ces options, la personne concern\u00e9e accepte cette transmission des donn\u00e9es personnelles n\u00e9cessaires pour le traitement de la facture ou de l&rsquo;achat avec acomptes, ou des contr\u00f4les d&rsquo;identit\u00e9 et de solvabilit\u00e9.<\/p>\n<p>Les donn\u00e9es \u00e0 caract\u00e8re personnel transmises sur Klarna sont g\u00e9n\u00e9ralement le pr\u00e9nom, le nom, l&rsquo;adresse, la date de naissance, le sexe, l&rsquo;adresse d&#8217;email, l&rsquo;adresse IP, le num\u00e9ro de t\u00e9l\u00e9phone, le num\u00e9ro de t\u00e9l\u00e9phone portable, ainsi que d&rsquo;autres donn\u00e9es n\u00e9cessaires au traitement d&rsquo;une facture ou d&rsquo;un achat avec acomptes. Le traitement du contrat d&rsquo;achat n\u00e9cessite \u00e9galement de telles donn\u00e9es personnelles, qui sont en relation avec la commande respective. En particulier, l&rsquo;\u00e9change d&rsquo;informations de paiement telles que coordonn\u00e9es bancaires, num\u00e9ro de carte, date de validit\u00e9 et code CVC, num\u00e9ro cumulatif, num\u00e9ro d&rsquo;article, donn\u00e9es sur les biens et services, prix et taxes, informations sur le comportement d&rsquo;achat pr\u00e9c\u00e9dent ou autres d\u00e9tails du situation financi\u00e8re de la personne concern\u00e9e.<\/p>\n<p>Le but de cette transmission des donn\u00e9es est notamment le contr\u00f4le d\u2019identification, l\u2019administration des paiements et la pr\u00e9vention des fraudes. Le responsable du traitement doit fournir \u00e0 Klarna des donn\u00e9es \u00e0 caract\u00e8re personnel, en particulier si un int\u00e9r\u00eat l\u00e9gitime \u00e0 la transmission existe. Les donn\u00e9es \u00e0 caract\u00e8re personnel \u00e9chang\u00e9es entre Klarna et la personne concern\u00e9e pour le traitement des donn\u00e9es sont transmises par Klarna aux agences \u00e9conomiques. Cette transmission est destin\u00e9e aux contr\u00f4les d&rsquo;identit\u00e9 et de solvabilit\u00e9.<\/p>\n<p>Klarna doit aussi transmettre les donn\u00e9es \u00e0 caract\u00e8re personnel aux affili\u00e9s (Klarna Group) et fournisseurs de service ou sous-traitants lorsque cela est n\u00e9cessaire pour remplir les obligations contractuelles ou traiter les donn\u00e9es dans la commande.<\/p>\n<p>Klarna collecte et utilise des donn\u00e9es et des information sur le comportement de paiement ant\u00e9rieur de la personne concern\u00e9e ainsi que des valeurs de probabilit\u00e9 pour son comportement futur (so-called scoring) afin de d\u00e9cider du raisonnement, de la mise en \u0153uvre ou de la fin d&rsquo;une relation contractuelle. Le calcul de la notation est effectu\u00e9 sur la base de m\u00e9thodes math\u00e9matiques et statistiques reconnues scientifiquement.<\/p>\n<p>La personne concern\u00e9e a la possibilit\u00e9 de r\u00e9voquer, \u00e0 toute moment, le consentement au traitement des donn\u00e9es \u00e0 caract\u00e8re personnel par Klarna. La revocation ne doit pas affecter le traitement des donn\u00e9es qui doivent etre trait\u00e9es, utilis\u00e9es ou transmises conform\u00e9ment au traitement des paiements (contractuel).\n<\/p>\n<p>Les dispositions de protection des donn\u00e9es applicables par Klarna sont accessibles sous https:\/\/cdn.klarna.com\/1.0\/shared\/content\/policy\/data\/de_de\/data_protection.pdf.<\/p>\n<h4>21. Mode de paiement: Dispositions relatives \u00e0 la protection des donn\u00e9es concernant Paypal comme processeur de paiement<\/h4>\n<p>Sur ce site Web, le responsable du traitement a int\u00e9gr\u00e9 des composants de PayPal. PayPal est un fournisseur de service de paiement en ligne. Les paiements sont trait\u00e9s via les soi-disant comptes Paypal, qui repr\u00e9sentent des comptes virtuels priv\u00e9s ou professionnels. PayPal est \u00e9galement capable de traiter des paiements virtuels via des cartes de cr\u00e9dit lorsqu&rsquo;un utilisateur ne poss\u00e8de pas de compte PayPal. Un compte PayPal est g\u00e9r\u00e9 via une adresse email, et c&rsquo;est pourquoi il n&rsquo;y a pas de num\u00e9ro de compte classiques. PayPal permet des paiements en ligne \u00e0 des tiers ou la r\u00e9ception des paiements. PayPal aussi accepte les fonctions de fiduciaire et offre des services de protection des acheteurs.<\/p>\n<p>L&rsquo; entreprise d&rsquo; exploitation europ\u00e9enne de PayPal est PayPal (Europe) S.\u00e0.r.l. et Cie, S.C.A., 22-24 Boulevard Royal L-2449, Luxemburg.<\/p>\n<p>Si la personne concern\u00e9e choisit \u00ab\u00a0PayPal\u00a0\u00bb comme l&rsquo;option de paiement dans la boutique en ligne pendant la proc\u00e9dure technique, nous transmettons automatiquement les donn\u00e9es de la personne concern\u00e9e \u00e0 PayPal. En choisissant ce mode de paiement, la personne concern\u00e9e accepte cette transmission des donn\u00e9es personnelles n\u00e9cessaires pour le traitement du paiement.<\/p>\n<p>Les donn\u00e9es \u00e0 caract\u00e8re personnel transmises sur PayPal sont g\u00e9n\u00e9ralement le pr\u00e9nom, le nom, l&rsquo;adresse, l&rsquo;adresse email, l&rsquo;adresse IP, le num\u00e9ro de t\u00e9l\u00e9phone, le num\u00e9ro de t\u00e9l\u00e9phone portable, ainsi que d&rsquo;autres donn\u00e9es n\u00e9cessaires au traitement du paiement. Le traitement du contrat d&rsquo;achat n\u00e9cessite \u00e9galement de telles donn\u00e9es personnelles, qui sont en relation avec la commande respective.<\/p>\n<p>La transmission des donn\u00e9es vise au traitement des paiements et \u00e0 la pr\u00e9vention de la fraude. Le responsable du traitement transf\u00e9rera des donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 Paypal, en particulier si un int\u00e9r\u00eat l\u00e9gitime \u00e0 la transmission est donn\u00e9. Les donn\u00e9es \u00e0 caract\u00e8re personnel \u00e9chang\u00e9es entre Paypal et le responsable du traitement des donn\u00e9es seront transmises par Paypal aux agences de cr\u00e9dit \u00e9conomique. La transmission est destin\u00e9e aux contr\u00f4les d&rsquo;identit\u00e9 et de solvabilit\u00e9.<\/p>\n<p>PayPal transmettra, si n\u00e9cessaire, des donn\u00e9es personnelles aux soci\u00e9t\u00e9s affili\u00e9es, fournisseurs de services ou sous-traitants si  cela est n\u00e9cessaire pour remplir les obligations contractuelles ou pour que les donn\u00e9es soient trait\u00e9es dans la commande.<\/p>\n<p>La personne concern\u00e9e a la possibilit\u00e9 de r\u00e9voquer, \u00e0 toute moment, le consentement au traitement des donn\u00e9es \u00e0 caract\u00e8re personnel par Klarna. La r\u00e9vocation ne doit pas affecter le traitement des donn\u00e9es qui doivent \u00eatre trait\u00e9es, utilis\u00e9es ou transmises conform\u00e9ment au traitement des paiements (contractuel).<\/p>\n<p>Les dispositions de protection des donn\u00e9es applicables par PayPal sont accessibles sous  https:\/\/www.paypal.com\/us\/webapps\/mpp\/ua\/privacy-full.<\/p>\n<h4>22. Mode de paiement: Dispositions relatives \u00e0 la protection des donn\u00e9es concernant Skrill comme processeur de paiement<\/h4>\n<p>Sur ce site Web, le responsable du traitement a int\u00e9gr\u00e9 des composants de Skrill. Skrill est un fournisseur de service de paiement en ligne. Les paiements sont effectu\u00e9s via le soi-disant portefeuille Skrill, un portefeuille \u00e9lectronique virtuel. Skrill est \u00e9galement capable de traiter des paiements virtuels via des cartes de cr\u00e9dit. Un portefeuille Skrill est g\u00e9r\u00e9 via une adresse email. Skrill permet des paiements en ligne \u00e0 des tiers ou la r\u00e9ception des paiements.<\/p>\n<p>L&rsquo; entreprise d&rsquo; exploitation de Skrill est Skrill Limited, 25 Canada Square, London E14 5LQ, United Kingdom.<\/p>\n<p>Si la personne concern\u00e9e choisit \u00ab\u00a0Skrill\u00a0\u00bb comme l&rsquo;option de paiement dans la boutique en ligne pendant le proc\u00e9dure technique, les donn\u00e9es de la personne sont automatiquement transmises \u00e0 Skrill. En choisissant ce mode de paiement, la personne concern\u00e9e accepte cette transmission des donn\u00e9es personnelles n\u00e9cessaires pour le traitement du paiement.<\/p>\n<p>Les donn\u00e9es \u00e0 caract\u00e8re personnel transmises sur Skrill sont le montant de l&rsquo;achat et l&rsquo;adresse e-mail, tous deux n\u00e9cessaires au traitement du paiement. La transmission des donn\u00e9es vise au traitement des paiements et \u00e0 la pr\u00e9vention de la fraude. Le responsable du traitement. Le responsable du traitement fournira \u00e9galement \u00e0 Skrill d&rsquo;autres donn\u00e9es \u00e0 caract\u00e8re personnel si un int\u00e9r\u00eat l\u00e9gitime \u00e0 la transmission existe. Les donn\u00e9es \u00e0 caract\u00e8re personnel \u00e9chang\u00e9es entre Skrill et la personne concern\u00e9e des donn\u00e9es seront trasnmises par Skrill aux agences de cr\u00e9dit \u00e9conomique. La transmission est destin\u00e9e aux contr\u00f4les d&rsquo;identit\u00e9 et de solvabilit\u00e9.<\/p>\n<p>Skrill transmettra, si n\u00e9cessaire, des donn\u00e9es personnelles aux soci\u00e9t\u00e9s affili\u00e9es, fournisseurs de services ou sous-traitants si  cela est n\u00e9cessaire pour remplir les obligations contractuelles ou pour que les donn\u00e9es soient trait\u00e9es dans la commande.<\/p>\n<p>La personne concern\u00e9e a la possibilit\u00e9 de r\u00e9voquer, \u00e0 toute moment, le consentement au traitement des donn\u00e9es \u00e0 caract\u00e8re personnel par Skrill. La r\u00e9vocation ne doit pas affecter le traitement des donn\u00e9es qui doivent \u00eatre trait\u00e9es, utilis\u00e9es ou transmises conform\u00e9ment au traitement des paiements (contractuel).<\/p>\n<p>Les dispositions de protection des donn\u00e9es applicables par Skrill sont accessibles sous   https:\/\/www.skrill.com\/en\/footer\/privacypolicy\/.<\/p>\n<h4>23. Mode de paiement: Dispositions relatives \u00e0 la protection des donn\u00e9es concernant Sofort\u00fcberweisung comme processeur de paiement<\/h4>\n<p>Sur ce site Web, le responsable du traitement a int\u00e9gr\u00e9 des composants de Sofort\u00fcberweisung. Sofort\u00fcberweisung est un fournisseur de service de paiement qui permet des paiements sans esp\u00e8ces de produits et services sur Internet. Sofort\u00fcberweisung est une proc\u00e9dure technique par laquelle le commer\u00e7ant en ligne re\u00e7oit imm\u00e9diatement une confirmation de paiement. Cela permet au commer\u00e7ant de livrer des biens, des services ou des t\u00e9l\u00e9chargements au client imm\u00e9diatement apr\u00e8s la commande.<\/p>\n<p>L&rsquo; entreprise d&rsquo; exploitation de Sofort\u00fcberweisung est Klarna Bank AB, Sveav\u00e4gen 46, 111 34 Stockholm, Schweden.<\/p>\n<p>Si la personne concern\u00e9e choisit \u00ab\u00a0transfert imm\u00e9diat\u00a0\u00bb comme l&rsquo;option de paiement dans la boutique en ligne pendant le proc\u00e9dure technique, les donn\u00e9es de la personne sont automatiquement transmises \u00e0 Sofort\u00fcberweisung. En choisissant ce mode de paiement, la personne concern\u00e9e accepte cette transmission des donn\u00e9es personnelles n\u00e9cessaires pour le traitement du paiement.<\/p>\n<p>Dans le cas du traitement des achats par transfert direct, l&rsquo;acheteur envoie le code PIN et le TAN \u00e0 Sofort GmbH. Sofort\u00fcberweisung effectue ensuite le transfert au commer\u00e7ant en ligne apr\u00e8s v\u00e9rification technique de l&rsquo;\u00e9tat du compte et r\u00e9cup\u00e9ration de donn\u00e9es suppl\u00e9mentaires pour v\u00e9rifier le compte. Le commer\u00e7ant en ligne est alors automatiquement inform\u00e9 de l&rsquo;ex\u00e9cution de la transaction financi\u00e8re.<\/p>\n<p>Les donn\u00e9es \u00e0 caract\u00e8re personnel transmises sur Sofort\u00fcberweisung sont g\u00e9n\u00e9ralement le pr\u00e9nom, le nom, l&rsquo;adresse, l&rsquo;adresse email, l&rsquo;adresse IP, le num\u00e9ro de t\u00e9l\u00e9phone, le num\u00e9ro de t\u00e9l\u00e9phone portable, ainsi que d&rsquo;autres donn\u00e9es n\u00e9cessaires au traitement du paiement. Le traitement du contrat d&rsquo;achat n\u00e9cessite \u00e9galement de telles donn\u00e9es personnelles, qui sont en relation avec la commande respective. Le responsable du traitement doit transmettre imm\u00e9diatement d&rsquo;autres donn\u00e9es \u00e0 caract\u00e8re personnel si un int\u00e9r\u00eat l\u00e9gitime \u00e0 la transmission existe. Les donn\u00e9es \u00e0 caract\u00e8re personnel \u00e9chang\u00e9es entre Sofort\u00fcberweisung et la personne concern\u00e9e des donn\u00e9es seront transmises par Sofort\u00fcberweisung aux agents de cr\u00e9dit \u00e9conomique. La transmission est destin\u00e9e aux contr\u00f4les d&rsquo;identit\u00e9 et de solvabilit\u00e9.<\/p>\n<p>Sofort\u00fcberweisung transmet, si n\u00e9cessaire, des donn\u00e9es personnelles aux soci\u00e9t\u00e9s affili\u00e9es, fournisseurs de services ou sous-traitants si  cela est n\u00e9cessaire pour remplir les obligations contractuelles ou pour que les donn\u00e9es soient trait\u00e9es.<\/p>\n<p>La personne concern\u00e9e a la possibilit\u00e9 de r\u00e9voquer, \u00e0 tout moment, le consentement au traitement des donn\u00e9es \u00e0 caract\u00e8re personnel par Sofort\u00fcberweisung. La r\u00e9vocation ne doit pas affecter le traitement des donn\u00e9es qui doivent \u00eatre trait\u00e9es, utilis\u00e9es ou transmises conform\u00e9ment au traitement des paiements (contractuel).<\/p>\n<p>Les dispositions de protection des donn\u00e9es applicables par Skrill sont accessibles sous https:\/\/www.klarna.com\/sofort\/datenschutz\/.<\/p>\n<h4>24. Base l\u00e9gale pour le traitement<\/h4>\n<p>Article 6(1)(a) RGPD sert comme la base l\u00e9gale aux op\u00e9rations de traitement pour lesquelles nous obtenons de consentement pour la finalit\u00e9 du traitement sp\u00e9cifique. Si le traitement des donn\u00e9es \u00e0 caract\u00e8re personnel est n\u00e9cessaire pour l&rsquo;ex\u00e9cution d&rsquo;un contrat auquel la personne concern\u00e9e est partie, par exemple lorsque des op\u00e9rations de traitement sont n\u00e9cessaires pour la fourniture de biens ou pour tout d&rsquo; autre service, le traitement est bas\u00e9 sur l&rsquo;article (1) (b) RGPD. La m\u00eame chose s&rsquo;applique a telles op\u00e9rations de traitement qui sont n\u00e9cessaires pour la r\u00e9alisation de mesures pr\u00e9contractuelles, par exemple dans le cas de demande concernant nos produits ou services. Si notre soci\u00e9t\u00e9 est soumise \u00e0 une obligation l\u00e9gale de traitement des donn\u00e9es \u00e0 caract\u00e8re personnel, par exemple pour le respect des obligations fiscales, le traitement est bas\u00e9 sur l&rsquo;art. 6 (1) (c) RGPD.<br \/>\nDans de certains cas, le traitement des donn\u00e9es \u00e0 caract\u00e8re personnel peut \u00eatre n\u00e9cessaire pour prot\u00e9ger les int\u00e9r\u00eats vitaux de la personne concern\u00e9e ou d&rsquo;une autre personne physique. Tel serait le cas, par exemple, si le visiteur \u00e9tait bless\u00e9 dans notre entreprise et que son nom, son \u00e2ge, ses donn\u00e9es d\u2019assurance maladie ou d\u2019autres informations vitales devaient \u00eatre transmises \u00e0 un m\u00e9decin, \u00e0 un h\u00f4pital ou \u00e0 un tiers. Ce traitement est alors bas\u00e9 sur l&rsquo;article 6(1)(d) RGPD.<br \/>\nEnfin, les op\u00e9rations de traitement peuvent \u00eatre bas\u00e9es sur l&rsquo;article 6(1)(f). Cette base l\u00e9gale est utilis\u00e9e pour des op\u00e9rations de traitement qui ne sont pas couverts par aucun des articles susmentionn\u00e9s, si le traitement est n\u00e9cessaire aux fins des int\u00e9r\u00eats l\u00e9gitimes poursuivis par notre soci\u00e9t\u00e9 ou par un tiers, sauf dans le cas o\u00f9 les int\u00e9r\u00eats ou les droits et libert\u00e9s fondamentaux de la personne concern\u00e9e ont pr\u00e9s\u00e9ance sur de tels int\u00e9r\u00eats qui exigent la protection des donn\u00e9es \u00e0 caract\u00e8re personnel. De telles op\u00e9rations de traitement sont particuli\u00e8rement permises car elles ont \u00e9t\u00e9 sp\u00e9cifiquement mentionn\u00e9es par le l\u00e9gislateur europ\u00e9en. Il a estim\u00e9 qu&rsquo;un int\u00e9r\u00eat l\u00e9gitime pouvait \u00eatre suppos\u00e9 si la personne concern\u00e9e \u00e9tait un client du responsable du traitement (R\u00e9cital 47 phrase 2 RGPD).\n<\/p>\n<h4>25. Les int\u00e9r\u00eats l\u00e9gitimes poursuivis par le responsable du traitement ou par un tiers. <\/h4>\n<p>Lorsque le traitement des donn\u00e9es personnelles est bas\u00e9 sur l&rsquo;article 6(1) (f) RGPD, notre int\u00e9r\u00eat l\u00e9gitime est d&rsquo; ex\u00e9cuter nos activit\u00e9s en faveur du bien-\u00eatre de tous nos employ\u00e9s et de nos actionnaires.<\/p>\n<h4>26. P\u00e9riode pour laquelle les donn\u00e9es \u00e0 caract\u00e8re personnel sont conserv\u00e9es<\/h4>\n<p>Les crit\u00e8res utilis\u00e9s pour d\u00e9terminer la p\u00e9riode de conservation est la p\u00e9riode de conservation l\u00e9gale respective. Apr\u00e8s l&rsquo;expiration de cette p\u00e9riode, les donn\u00e9es sont syst\u00e9matiquement supprim\u00e9es, tant qu&rsquo;elles ne sont plus n\u00e9cessaires \u00e0 l&rsquo;ex\u00e9cution du contrat ou \u00e0 l&rsquo;ouverture d&rsquo;un contrat.<\/p>\n<h4>27. Fourniture de donn\u00e9es \u00e0 caract\u00e8re personnel comme des exigences l\u00e9gales ou contractuelles; Exigence n\u00e9cessaire pour conclure un contrat; Obligation de la personne concern\u00e9e de fournir les donn\u00e9es \u00e0 caract\u00e8re personnel; cons\u00e9quences possibles de la non-fourniture de ces donn\u00e9es<\/h4>\n<p>Nous clarifions que la fourniture des donn\u00e9es \u00e0 caract\u00e8re personnel est requise en partie par la loi (par ex. des dispositions fiscales) ou des dispositions contractuelles (par ex. information sur le partenaire contractuel).<\/p>\n<p>Parfois, il peut \u00eatre n\u00e9cessaire de conclure un contrat avec des donn\u00e9es que la personne concern\u00e9e nous a fournies et qu&rsquo;ils peuvent ensuite \u00eatre trait\u00e9s par nous. La personne concern\u00e9e est, par exemple, oblig\u00e9e de nous fournir des donn\u00e9es \u00e0 caract\u00e8re personnel quand notre entreprise signe un contrat avec lui. La non-fourniture des donn\u00e9es \u00e0 caract\u00e8re personnel  aurait pour cons\u00e9quence que le contrat avec la personne concern\u00e9e ne pourrait \u00eatre conclu.<\/p>\n<p>Avant que les donn\u00e9es \u00e0 caract\u00e8re personnel sont fournies par la personne concern\u00e9e, la personne concern\u00e9e doit contacter un employ\u00e9. L&#8217;employ\u00e9 clarifie a la personne concern\u00e9e, si la fourniture des donn\u00e9es \u00e0 caract\u00e8re personnel est n\u00e9cessaire par la loi ou par un contrat ou c&rsquo;est n\u00e9cessaire pour la conclusion d&rsquo;un contrat, s&rsquo;il existe une obligation de fournir les donn\u00e9es personnelles et les cons\u00e9quences de la non-fourniture du personnel des donn\u00e9es \u00e0 caract\u00e8re personnel.\n<\/p>\n<h4>28. Existence d&rsquo;un m\u00e9canisme de prise de d\u00e9cision automatis\u00e9<\/h4>\n<p>En tant qu&rsquo;entreprise responsable, nous n&rsquo;utilisons pas de processus de d\u00e9cision ou de profilage automatique.<\/p>\n<p>This Privacy Policy has been generated by the Privacy Policy Generator of the <a href=\"https:\/\/dg-datenschutz.de\/services\/external-data-protection-officer\/?lang=en\">DGD &#8211; Your External DPO<\/a> that was developed in cooperation with  <a href=\"https:\/\/www.wbs-law.de\/eng\/\">German Lawyers<\/a> from WILDE BEUGER SOLMECKE, Cologne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Politique de confidentialit\u00e9 Nous sommes ravis que vous exprimez de l&rsquo;int\u00e9r\u00eat pour notre entreprise. La protection des donn\u00e9es est une priorit\u00e9 tr\u00e8s \u00e9lev\u00e9e du management de Cincomedia GmbH. L&rsquo; utilisation des pages Internet de Cincomedia GmbH est possible sans aucune indication des donn\u00e9es \u00e0 caract\u00e8re personnel. Cependant, si une personne concern\u00e9e veux utiliser des services &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"terms_conditions.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-28674","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Politique de confidentialit\u00e9 - camperstime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.camperstime.com\/fr\/terms-and-conditions\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 - camperstime\" \/>\n<meta property=\"og:description\" content=\"Politique de confidentialit\u00e9 Nous sommes ravis que vous exprimez de l&rsquo;int\u00e9r\u00eat pour notre entreprise. La protection des donn\u00e9es est une priorit\u00e9 tr\u00e8s \u00e9lev\u00e9e du management de Cincomedia GmbH. L&rsquo; utilisation des pages Internet de Cincomedia GmbH est possible sans aucune indication des donn\u00e9es \u00e0 caract\u00e8re personnel. Cependant, si une personne concern\u00e9e veux utiliser des services ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.camperstime.com\/fr\/terms-and-conditions\" \/>\n<meta property=\"og:site_name\" content=\"camperstime\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-25T04:02:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"64 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.camperstime.com\/fr\/terms-and-conditions\",\"url\":\"https:\/\/www.camperstime.com\/fr\/terms-and-conditions\",\"name\":\"Politique de confidentialit\u00e9 - camperstime\",\"isPartOf\":{\"@id\":\"https:\/\/www.camperstime.com\/fr#website\"},\"datePublished\":\"2015-04-23T12:57:21+00:00\",\"dateModified\":\"2019-10-25T04:02:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.camperstime.com\/fr\/terms-and-conditions#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.camperstime.com\/fr\/terms-and-conditions\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.camperstime.com\/fr\/terms-and-conditions#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.camperstime.com\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.camperstime.com\/fr#website\",\"url\":\"https:\/\/www.camperstime.com\/fr\",\"name\":\"camperstime\",\"description\":\"Themen und Artikel rund um einen Campingurlaub\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.camperstime.com\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 - camperstime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.camperstime.com\/fr\/terms-and-conditions","og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 - camperstime","og_description":"Politique de confidentialit\u00e9 Nous sommes ravis que vous exprimez de l&rsquo;int\u00e9r\u00eat pour notre entreprise. La protection des donn\u00e9es est une priorit\u00e9 tr\u00e8s \u00e9lev\u00e9e du management de Cincomedia GmbH. L&rsquo; utilisation des pages Internet de Cincomedia GmbH est possible sans aucune indication des donn\u00e9es \u00e0 caract\u00e8re personnel. Cependant, si une personne concern\u00e9e veux utiliser des services ...","og_url":"https:\/\/www.camperstime.com\/fr\/terms-and-conditions","og_site_name":"camperstime","article_modified_time":"2019-10-25T04:02:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"64 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.camperstime.com\/fr\/terms-and-conditions","url":"https:\/\/www.camperstime.com\/fr\/terms-and-conditions","name":"Politique de confidentialit\u00e9 - camperstime","isPartOf":{"@id":"https:\/\/www.camperstime.com\/fr#website"},"datePublished":"2015-04-23T12:57:21+00:00","dateModified":"2019-10-25T04:02:15+00:00","breadcrumb":{"@id":"https:\/\/www.camperstime.com\/fr\/terms-and-conditions#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.camperstime.com\/fr\/terms-and-conditions"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.camperstime.com\/fr\/terms-and-conditions#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.camperstime.com\/fr"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.camperstime.com\/fr#website","url":"https:\/\/www.camperstime.com\/fr","name":"camperstime","description":"Themen und Artikel rund um einen Campingurlaub","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.camperstime.com\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.camperstime.com\/fr\/wp-json\/wp\/v2\/pages\/28674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camperstime.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.camperstime.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.camperstime.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camperstime.com\/fr\/wp-json\/wp\/v2\/comments?post=28674"}],"version-history":[{"count":0,"href":"https:\/\/www.camperstime.com\/fr\/wp-json\/wp\/v2\/pages\/28674\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.camperstime.com\/fr\/wp-json\/wp\/v2\/media?parent=28674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}